{"id":127,"date":"2008-03-11T21:55:37","date_gmt":"2008-03-11T19:55:37","guid":{"rendered":"http:\/\/bernd-leitenberger.de\/blog\/2008\/03\/11\/abbildende-spektrometer\/"},"modified":"2010-08-16T14:55:43","modified_gmt":"2010-08-16T12:55:43","slug":"abbildende-spektrometer","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2008\/03\/11\/abbildende-spektrometer\/","title":{"rendered":"Abbildende Spektrometer"},"content":{"rendered":"\n<p>Heute mal wieder ein l&auml;ngerer Beitrag getreu dem Motto &quot;Da haben wir mal \twieder was gelernt&quot;. Es geht um eine Klasse von Instrumenten, die unbemerkt \teine Bl&uuml;te erlebt hat: Abbildende Spektrometer.<\/p>\n<p>Zuerst einmal eine Erkl&auml;rung was Spektroskopie ist: Es ist die \tAufspaltung von elektromagnetischen Wellen nach ihrer Frequenz in einzelne \tMesswerte. Das ganze kann man bei allen elektromagnetischen Wellen machen, \tvon Gammastrahlen bis hin zu Langwellen. Ein Radio ist z.B. ein Spektrometer \tf&uuml;r UKW Wellen. Sie selektieren einen Bereich durch die Wahl der Frequenz \tund w&uuml;rden sie durch alle Frequenzen durchgehen und dabei jeweils die \tLautst&auml;rke in der Y Achse notieren (die X Achse ist f&uuml;r die Frequenz \tbestimmt) so h&auml;tten sie ein Spektrogramm.<\/p>\n<p>Nun die Instrumente die ich nun bespreche arbeiten im sichtbaren Licht \tund im Infraroten. Die Sonne sendet Strahlung dieser Wellenl&auml;nge aus und \tschon im Spektrum des Sonnenlichts findet man Einbr&uuml;che &#8211; scharf begrenzte \tLinien. Diese entstehen, weil Atome in der Korona und Photosph&auml;re der Sonne \tEnergie aus dem Licht aufnehmen und dabei Elektronen von einer Bahn auf eine \tandere springen. Jede Wellenl&auml;nge entspricht einer Energie und weil diese \tSpr&uuml;nge nur von einer Bahn zur anderen gehen, aber nie in den Zwischenraum \tdazwischen, wird nur Energie einer bestimmten Wellenl&auml;nge absorbiert (analog \twie wenn sie einen Ball genau in einem Basketballkorb versenken wollen &#8211; \tdazu muss er genauso so hoch wie der Korb geworfen werden &#8211; zu wenig und er \terreicht den Korb nicht, zu viel und er prallt am Schild ab.)<\/p>\n<p><!--more--><\/p>\n<p>Kommt nun das Sonnenlicht auf einen Planeten oder Mond, so absorbieren \tdie Atmosph&auml;re und die Oberfl&auml;che auch Energie. Die Energie regt \tAtombindungen zum Schwingen, Oszillieren und Rotieren an. Auch hier h&auml;ngt \tdie Wellenl&auml;nge von der Bindung ab. Allerdings gibt es hier einen breiten \tBereich, weil die Bindung unterschiedliche Energien aufnehmen kann. Als ich \tnoch Lebensmittelchemiker war, und es keine Computer f&uuml;r normale Studenten \tgab, musste man z.B. unbekannte Materialen durch Spektren vergleich \tbestimmen. Man schaute in der Literatur nach welche Bindungen wo in welchem \tMuster absorbieren, dann hatte man einige Bindungen des Molek&uuml;ls. Damit \tsuchte man nach Substanzen die diese Bindungen enthielten. War dort ein Teil \tdes Spektrums identisch, so hatte man einen Molek&uuml;lteil identifiziert z.B. \teinen aromatischen Ring, und man konnte nach &auml;hnlichen Verbindungen suchen, \twelche den Rest des Spektrums (die dort identifizierten Bindungen) \tenthielten. Das war zum einen sehr lehrreich, aber auch sehr &ouml;de. Ich kann \tmich noch erinnern, dass ich knapp 2 Jahre nach dem Uni Studium in einem \tPraktikum dieselbe Aufgabe von einem Laborleiter bekam, der mich wohl damit \tabwimmeln wollte. Dummerweise hatte er eine Substanz rausgesucht, die ich \tschon mal identifizieren musste und so hatte ich die L&ouml;sung nach einer \thalben Stunde anstatt der vom Laborleiter erhofften Tage.<\/p>\n<p>Diffiziler ist es wenn sich die Spektren &uuml;berlagern, weil in der \tAtmosph&auml;re mehrere Substanzen sind oder der Boden aus mehreren Mineralien \tbesteht. Doch auch das ist l&ouml;sbar. In meinem ersten Staatsexamen bestimmte \tich 3 rote Farbstoffe, nicht wie &uuml;blich durch D&uuml;nnschichtchromatographie, \tsondern durch Spektren vergleich. Spektren liefern Daten &uuml;ber die \tmineralogische Zusammensetzung des Bodens und der Atmosph&auml;re. Wie stark eine \tSubstanz absorbiert ist ein Ma&szlig; f&uuml;r ihre Menge. Kurzum: Man erh&auml;lt so die \tZusammensetzung von Planeten und Atmosph&auml;ren &#8211; ohne eine direkte Analyse. \t<\/p>\n<p>Mineralien absorbieren Licht im sichtbaren Bereich bis zum nahen Infrarot. Organische Stoffe und fl&uuml;ssige bis feste (extrem kalte) Gase im nahen bis mittleren Infrarot und Atmosph&auml;rengase im mittleren bis fernen infrarot. Daher haben zahlreiche Raumsonden ein Spektrometer f&uuml;r das sichtbare Licht und Infrarot an Bord. Ein solch klassisches Instrument besteht aus einem Teleskop, das Licht b&uuml;ndelt. Im Strahlengang ist dann eine Blende, die nur noch einen Schlitz durchl&auml;sst. Das begrenzt das Licht auf eine Stelle. Das Licht trifft dann auf ein Gitter, wo es durch Brechung in Spektralfarben aufgespalten wird (vergleichbar dem Regenbogen den eine CD erzeugt9. Das so entstandene Spektrum ist dann ein langgezogener Streifen, der entweder von einer sehr langen Zeile von Detektorelementen oder wenigen Detektoren, die mit einem Schrittmotor entlang dem Spektrum bewegt werden, erfasst werden.<\/p>\n<p>Man erh&auml;lt so ein Spektrum mit sehr hoher spektraler Aufl&ouml;sung, d.h. \tjedes Detektorelement deckt nur einen kleinen Wellenl&auml;ngenbereich ab. \tAllerdings bekommt man es nur von einem Punkt, und man hat zwar so eine sehr \tgute spektrale Aufl&ouml;sung, aber eine sehr kleine r&auml;umliche Aufl&ouml;sung. Gute \tSpektrometer dieser Art, wie das PFS haben z.B. 10000-20000 Me&szlig;punkte, aber \tihre r&auml;umliche Aufl&ouml;sung ist sehr gering. CIRS an Bord von Cassini braucht \tsehr viele Vorbeifl&uuml;ge um auch nur eine halbwegs komplette Karte mit \tMessungen von Titan anzufertigen. Von den anderen Monden gibt es nur \tMessungen kleiner Ausschnitte oder eben gleich des ganzen Mondes.<\/p>\n<p> \t<img loading=\"lazy\" decoding=\"async\" alt=\"CRISM\" src=\"\/img\/crism-1.jpeg\" width=\"600\" height=\"892\" style=\"float: left\"\/>Seit \tAnfang der 90 er Jahre hat man neue Instrumente entwickelt, eine Art Zwitter \tzwischen Spektrometer und CCD Kamera &#8211; Die Optik und das Gitter ist wie bei \teinem klassischen Spektrometer. Doch dahinter setzt nun ein Array CCD \tDetektor, z.B. mit 256 x 256 Pixeln.<\/p>\n<p>In der Y Richtung (Spalte) bekommt man den Schlitz zu sehen, also die \tr&auml;umliche Information. In der X Richtung (Zeile), das Spektrum also die \tspektrale Information. Das alleine ist nicht viel besser als ein normales \tSpektrometer &#8211; man hat eben anstatt wenigen nun 256 Bildpunkte \tuntereinander. Doch wenn man nun durch einen Schrittmotor das Teleskop \tbewegt, erh&auml;lt man Spalte f&uuml;r Spalte ein zweidimensionales Bild. Der Nutzen \tist dann doppelt da: Die r&auml;umliche Aufl&ouml;sung ist deutlich h&ouml;her, als bei \teinem klassischen Spektrometer und man kann neben dem Spektrum eines Punktes \tauch ein Bild des Himmelsk&ouml;rpers in einer Spektralfarbe machen und so z.B. \tFalschfarbenaufnahmen machen bei denen man mit Farben das Vorkommen von \tbestimmten Mineralien kodiert.<\/p>\n<p>Der Hauptnachteil dieser Instrumente ist ihre enorme Datenmenge. Sie \tliefern pro Punkt viel mehr Daten als eine Kamera, selbst wenn man bedenkt \tdas IR Sensorelemente viel gr&ouml;ber aufl&ouml;sen als CCD f&uuml;rs sichtbare Licht. F&uuml;r \tein Bild eines Mondes von 256 x 256 Pixel r&auml;umlich, kommen pro Punkt 256 \tspektakle Messungen, also die 256 fache Menge einer Kamera derselben \tAufl&ouml;sung. Daher betreibt man Cassinis Instrument meist in einem \tSummenmodus, indem es nur 64 x 64 x 64 Elemente erzeugt. Omega an Bord von \tMars Express nutzt schon 352 Spektralkan&auml;le. Heutige CCD sind bis 1024 x \t1024 Pixel gro&szlig;, w&uuml;rden also noch viel h&ouml;here r&auml;umliche und spektrale \tAufl&ouml;sungen erlauben, doch da kommt man an die Grenze die man &uuml;bertragen \tkann.<\/p>\n<p>Heute findet man abbildendes Spektrometer an Bord fast jeder Raumsonde &#8211; \tAuf Dawn, Rosetta und Venus Express z.B. VIRTIS. An Bord von Mars Express \tist es Omega. An Bord des MRO ist es CRISM und SIR und M3 an Bord von \tChandrayaan 1. Diese Instrumente sagen uns mehr als Kameras und sie werden \timmer wichtiger &#8211; Die Oberfl&auml;che des Mars ist heute so gut bekannt wie man \tsie f&uuml;r geologische Untersuchungen kennen muss, doch ihre Zusammensetzung \tist noch kaum erforscht. VIMS konnte auf den Saturnmonden unterscheiden wo \tim eis sich Ammoniak, Kohlenmonoxid und Methan befindet, wo organische \tStoffe &#8211; auf den Bildern sehen die Monde absolute einfarbig aus. Und VIRTIS \tsieht im infraroten Bodenstrukturen durch unterschiedliche Temperaturen, und \tsoll so auch nach hei&szlig;en Quellen (Vulkanen) suchen.<\/p>\n<p>Sodele, bis in ein paar Tagen, derzeit habe ich viel zu tun&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute mal wieder ein l&auml;ngerer Beitrag getreu dem Motto &quot;Da haben wir mal wieder was gelernt&quot;. Es geht um eine Klasse von Instrumenten, die unbemerkt eine Bl&uuml;te erlebt hat: Abbildende Spektrometer. Zuerst einmal eine Erkl&auml;rung was Spektroskopie ist: Es ist die Aufspaltung von elektromagnetischen Wellen nach ihrer Frequenz in einzelne Messwerte. Das ganze kann man [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[1380,70],"class_list":["post-127","post","type-post","status-publish","format-standard","hentry","category-raumfahrt","tag-instrumente","tag-spektrometer","entry"],"a3_pvc":{"activated":false,"total_views":300,"today_views":0},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":18542,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/02\/25\/mush-schleuder-auf-dem-mond\/","url_meta":{"origin":127,"position":0},"title":"Musks &#8222;Schleuder&#8220; auf dem Mond","author":"Bernd Leitenberger","date":"25. Februar 2026","format":false,"excerpt":"Da k\u00fcndigt Jeff Bezos am 31.1.2026 an, das Blue Origin den Suborbitaltourismus f\u00fcr mindestens zwei Jahre einstellen will, um sich ganz auf den Blue Moon Mondlander zu konzentrieren. Und kaum ist das gesackt, will nun Elon Musk dann gleich eine ganze Stadt auf dem Mond bauen. (9.2.2026). Zufall? Anstatt das\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg07.met.vgwort.de\/na\/64ef0834094b4d9b9af02f70b7ad22f7","width":350,"height":200},"classes":[]},{"id":18469,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/11\/13\/operation-fishbowl\/","url_meta":{"origin":127,"position":1},"title":"Operation Fishbowl","author":"Bernd Leitenberger","date":"13. November 2025","format":false,"excerpt":"Hallo, ich schreibe weiter an meinem Buch, die Auskopplung der Thor und Delta aus dem Buch \u00fcber die US-Tr\u00e4gerraketen. Und wie immer nutze ich die Zeit noch was zu erg\u00e4nzen. Seitens des Einsatzes der Thor bzw. Delta als Satellitentr\u00e4ger gibt es wenig Neues zu schreiben da habe ich schon beim\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg","width":350,"height":200,"srcset":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1.5x"},"classes":[]},{"id":18519,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/02\/03\/warum-elon-musk-zum-mars-will\/","url_meta":{"origin":127,"position":2},"title":"Warum Elon Musk zum Mars will","author":"Bernd Leitenberger","date":"3. Februar 2026","format":false,"excerpt":"K\u00fcrzlich war ich bei einem Vortrag \u00fcber das Alphateilchenspektrometer, das 1997 bei der Mars Mission Sojourner als deutsches Experiment (Max-Planck-Institut f\u00fcr Chemie aus Mainz) mitflog, was damals etwas Besonderes war. In der Unterhaltung nach dem Vortrag meinte der inzwischen emittierte Wissenschaftler, dass sich sogar Elon Musk f\u00fcr die Ergebnisse interessiert\u2026","rel":"","context":"In &quot;M\u00fcnchhausens Kolumne&quot;","block_context":{"text":"M\u00fcnchhausens Kolumne","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/satire\/muenchhausen\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/644d63c4123243a3900cf5c92fa7398b","width":350,"height":200},"classes":[]},{"id":18547,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/03\/04\/quo-vadis-artemis\/","url_meta":{"origin":127,"position":3},"title":"Quo Vadis Artemis?","author":"Bernd Leitenberger","date":"4. M\u00e4rz 2026","format":false,"excerpt":"Ich muss mal meine nicht vorhandene humanistische Bildung heraush\u00e4ngen, sprich Latein kann ich nicht, aber ich habe in meiner Jugend gerne Monumentalschinken angeschaut und da gibt es den ber\u00fchmtem Film \"Quo Vadis\" mit der ersten gro\u00dfen Rolle f\u00fcr Peter Ustinov als Nero. Das Zitat ist bekannt: Petrus flieht aus Rom,\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"\/img\/artemis-2026-2028.jpg","width":350,"height":200,"srcset":"\/img\/artemis-2026-2028.jpg 1x, \/img\/artemis-2026-2028.jpg 1.5x, \/img\/artemis-2026-2028.jpg 2x, \/img\/artemis-2026-2028.jpg 3x, \/img\/artemis-2026-2028.jpg 4x"},"classes":[]},{"id":4557,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2011\/04\/03\/atom-und-wahlnachlese\/","url_meta":{"origin":127,"position":4},"title":"Atom- und Wahlnachlese","author":"Bernd Leitenberger","date":"3. April 2011","format":false,"excerpt":"Nun einige Wochen nach dem Super-Gau von Japan wird es an der Zeit f?r eine Nachlese und zwar eine etwas allgemeiner gehaltene. Ich m?chte an dieser Stelle mal meine Einstellung zur Kernkraft in den letzten Jahrzehnten reflektieren. Ich war urspr?nglich f?r Kernkraft. Wie viele andere, glaubte ich an umweltfreundliche Energie\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18504,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/25\/die-glorreichen-10-satellitenrekorde\/","url_meta":{"origin":127,"position":5},"title":"Die glorreichen 10 &#8211; Satellitenrekorde","author":"Bernd Leitenberger","date":"25. Januar 2026","format":false,"excerpt":"Ich denke, es wird mal wieder Zeit f\u00fcr etwas leichte Unterhaltung die etwas Wissen vermittelt. Also einen Blog \u00fcber 10 Rekorde bei Satelliten, die ihr vielleicht noch nicht kennt. Um eines klarzustellen - es geht nur um Satelliten. Raumsonden sind au\u00dfen vor, weil bei ihnen vieles anderes ist, so kann\u2026","rel":"","context":"In &quot;Die Glorreichen 10&quot;","block_context":{"text":"Die Glorreichen 10","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/die-glorreichen-10\/"},"img":{"alt_text":"","src":"\/img\/1kgsats.png","width":350,"height":200,"srcset":"\/img\/1kgsats.png 1x, \/img\/1kgsats.png 1.5x, \/img\/1kgsats.png 2x, \/img\/1kgsats.png 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/127\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}