{"id":12796,"date":"2017-10-03T10:55:27","date_gmt":"2017-10-03T08:55:27","guid":{"rendered":"https:\/\/www.bernd-leitenberger.de\/blog\/?p=12796"},"modified":"2017-10-03T10:55:27","modified_gmt":"2017-10-03T08:55:27","slug":"zwei-jahrestage-75-jahre-a-4-und-60-jahre-sputnik","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2017\/10\/03\/zwei-jahrestage-75-jahre-a-4-und-60-jahre-sputnik\/","title":{"rendered":"Zwei Jahrestage. 75 Jahre A-4 und 60 Jahre Sputnik"},"content":{"rendered":"<p>Kommen nun heute und morgen. Zuerst einmal ist das der 75-ste Jahrestag des ersten erfolgreichen Starts einer A-4 am 3.10.1942. Dann morgen, am 4.10. der 60-ste Jahrestag des Starts von Sputnik 1. Viel ist zu beiden geschrieben worden. Schwer ist es da noch Neues beizutragen, doch ich will es mal probieren. Bei der A-4 wurde bei Skyweek 2.0 die <a href=\"https:\/\/skyweek.wordpress.com\/2017\/10\/01\/wurde-vor-75-jahren-der-weltraum-erreicht\/\">Diskussion<\/a> erw&auml;hnt, ob sie nun die Grenze zum Weltraum erreicht hat. Der erste Schuss ging in 84,5 km H&ouml;he. Nach der landl&auml;ufigen Definition ist die Grenze zum Weltraum in 100 km H&ouml;he. Doch das ist eben nur eine Definition. Man kann auch anders definieren. Die USA haben mal sie auf 50 Landmeilen runtergesetzt, dass ihre X-15 Flieger auch den Weltraum erreichten. Da w&auml;re sie dr&uuml;ber. Ich will mal diskutieren, was man als Kriterium nehmen k&ouml;nnte.<!--more--><\/p>\n<h3 class=\"western\">Kriterium 1: Weltraum ist da, wo die Luft zu d&uuml;nn f&uuml;r andere Gef&auml;hrte ist.<\/h3>\n<p>Ein Kriterium das man nehmen kann bezieht sich auf die Technologie. Wir kommen ja nicht so in den Weltraum wir brauchen ein technisches Ger&auml;t und da kann man nun einfach sagen: Ger&auml;te, die irgendwie von der Luft abh&auml;ngig sind, sind eine Kategorie und Ger&auml;te die auch im Weltraum arbeiten, eine andere. Das erste w&auml;ren Flugzeuge, sowohl mit Propeller wie Strahlantrieb und Ballone. Das zweiet w&auml;ren Raketen. Flugzeuge sto&szlig;en schon bei 30 km an ihre Grenzen, weil dann die Luft zu d&uuml;nn wird, um als Verbrennungstr&auml;ger f&uuml;r D&uuml;sentriebwerke zu dienen. Mit RAMJets sollte man h&ouml;her kommen. Leider gibt es hier wenige Versuche gro&szlig;e H&ouml;hen zu erreichen. Ballone erreichen mit Nutzlast ohne Problem 30-35 km H&ouml;he. Ein NASA-Ballon hat 2006 schon 49 km <a href=\"http:\/\/www.spiegel.de\/wissenschaft\/weltall\/neuer-rekord-nasa-ballon-stieg-auf-49-kilometer-hoehe-a-211145.html\">erreicht<\/a>. Eine Mig 25 hat im Parabelflug immerhin 37,65 km erreicht. Regul&auml;r liegt der Rekord (ohne Parabel) bei 26,32 km.<\/p>\n<p>Diese H&ouml;hen liegen also weit unterhalb der normalen Grenze zum Weltraum. Ich rechne aber damit, dass man wenn man Ramjets baut, noch deutlich h&ouml;her kommt. Denn sonst machen die keinen Sinn. Bei nur 50 km H&ouml;he m&uuml;sste eine Oberstufe noch sehr viel Arbeit leisten. Nach Wikipedia soll bei Scramjets sie Maximalh&ouml;he bei 75 km liegen, was ziemlich nahe an der heutigen Definition ist.<\/p>\n<h3 class=\"western\">Kriterium 2: Weltraum ist da, wo die Luft in den Weltraum &uuml;bergeht.<\/h3>\n<p>Okay, ich gebe zu das Kriterium ist weich. Es ist ja nicht so das unsere Atmosph&auml;re bei 100 km abrupt aufh&ouml;rt. Sie wird vielmehr immer d&uuml;nner. Satelliten werden noch in 200 km H&ouml;he so stark abgebremst das innerhalb weniger Wochen vergl&uuml;hen. In 400 km H&ouml;he liegt man bei &uuml;ber einem Jahr und bei 600 km H&ouml;he im Bereich von Jahrzehnten, nat&uuml;rlich stark abh&auml;ngig von der Form eines Satelliten. Zudem ist die Dichte sehr stark abh&auml;ngig von der Sonnenaktivit&auml;t \u2013 bei hoher Aktivit&auml;t str&ouml;men viele Protonen und Elektronen auf die Atmosph&auml;re und &uuml;bertragen durch Zusammensto&szlig; Energie und sie dehnt sich aus. Aber ich denke man kann trotzdem ein Kriterium anwenden. N&auml;mlich die Zusammensetzung. Am Erdboden besteht die Luft aus Molek&uuml;len. In der oberen Atmosph&auml;re aus Radikalen und Ionen. Deswegen wird sie auch Ionosph&auml;re genannt. Diese beginnt bei 70 bis 90 km, stark abh&auml;ngig von der Sonnenaktivit&auml;t. Nimmt man die Mitte, so liegt man bei 80 km. Das w&auml;re auch eine gangbare Definition.<\/p>\n<h3 class=\"western\">Kriterium 3: Der Weltraum beginnt da, wo ein Satellit mindestens einen Umlauf schafft.<\/h3>\n<p>Was mich an den Definitionen st&ouml;rt, die es bisher gab, ist das man allesamt versucht, kleine Hopser zu Weltraummissionen umzudefinieren. F&uuml;r mich beginnt Weltraumfahrt da, wenn man einen Orbit erreicht. Alles andere ist suborbital. Da ist es dann wurst ob eine Rakete 80 oder 100 km H&ouml;he erreicht. H&ouml;henforschungsraketen die leicht &uuml;ber 100 km kommen (die meisten weitaus h&ouml;her) hei&szlig;en ja auch nicht Weltraumforschungsraketen.<\/p>\n<p>Die Untergrenze ist da, wo das Auseinanderbrechen eines Satelliten beginnt. Das ist bei 80 km H&ouml;he der Fall, sofern der Satellit nicht eine spezielle form hat (die Keyhole 1-7 in Form einer Gewehrpatrone kamen bis auf 90 km an die erde heran). Solarzellen und andere leichte, gro&szlig;e Fl&auml;chen, k&ouml;nne schon vorher abgehen. Vor allem aber ist die Abbremsung ein sich selbst beschleunigender Prozess. Verliert der Satellit h&ouml;he, so sinkt er weiter ab, was zu noch schnellerem Absinken f&uuml;hrt. Daher mein Kriterium: Die Mindesth&ouml;he ist die, bei der ein Satellit nach einem Umlauf auf 80 km H&ouml;he abgesunken ist. Denn dort beginnen fragile Satelliten auseinanderzubrechen.<\/p>\n<p>Das ist nat&uuml;rlich auch abh&auml;ngig von der Art des Satelliten und der Sonnenaktivit&auml;t. Eine Kugel aus Uran (Geod&auml;seisatelliten) sinkt langsamer als ein Ballon. Wenn man einen 1U Cubesat als Referenz nimmt (im Vergleich zu gr&ouml;&szlig;eren Satelliten ung&uuml;nstiges Oberfl&auml;che\/Masse Verh&auml;ltnis) und eine mittlere Sonnenaktivit&auml;t von 160 SFU und einen AP-Index von 12. so kann man simulieren, aus welcher Ausgangsh&ouml;he man nach einem Umlauf auf 80 km H&ouml;he gesunken ist. Mit einem einfachen Modell komme ich auf 88 km Ausgangsh&ouml;he.<\/p>\n<p>Wenn man als Kriterium einen Tag nimmt, so sind es 153 km. Physikalisch macht ein Umlauf eher Sinn. Denn wenn man nicht mal einmal die Erde umrunde, dann k&ouml;nnte man den Satelliten auch als suborbitale Nutzlast z.B. einer ICBM ansehen. (Gab es auch mal). Technisch macht wohl ein Tag mehr Sinn, denn im Orbit muss man den Satelliten ja in Betrieb nehmen und zumindest eine kleine Mission durchf&uuml;hren.<\/p>\n<h3 class=\"western\">Sputnik und seine Folgen<\/h3>\n<p>Kommen wir zum Sputnik. Ich will nicht auf das Ereignis selbst eingehen, sonder um die Auswirkungen. Den Sputnikstart musste Koroljow ja noch der milit&auml;rischen F&uuml;hrung als Testflug verkaufen. Das Medienecho vor allem im Westen f&uuml;hrte dazu, dass man bald nachlegte. Sputnik 2 folgte zum Jahrestag der Oktoberrevolution. Der Sputnikschock folgte eigentlich mit Sputnik 2. Man wusste im Westen ja nicht, mit welcher Tr&auml;gerrakete der Satellit gestartet wurde. Die USA planten Explorer und Vanguard. Die waren maximal 20 kg schwer. Sputnik 1 war 80 kg schwer, also deutlich schwerer, doch 80 kg w&auml;ren mit den Tr&auml;gern und optimierten Oberstufen auch m&ouml;glich. Sputnik 2 wog &uuml;ber 500 kg und Sputnik 3 im Mai 1958 dann 1.500 kg. Damit war klar, das Russland eine ICBM hatte, die die USA erreichen konnte. Das war die eigentliche Bedeutung des Satellitenstarts.<\/p>\n<p>Was er ausgel&ouml;st hatte, war ein Wettlauf. Nicht nur ein Bemannter zum Mond, sondern auch ein unbemannter. Er ist mir beim Schreiben meines Buches &uuml;ber die Raumsonden wieder vergegenw&auml;rtigt worden. Es ist frustrierend Dutzende von Raumsonden aufzuf&uuml;hren, die nicht ihr Ziel erreichten, weil man sie &uuml;berhastet oder mit unerprobten Tr&auml;gern startete. Seitens der USA waren dies die ersten Jahre. Auch hier versuchte man mit den fr&uuml;hen Pioneers und Ranger die UdSSR zu &uuml;bertrumpfen. Auch Mariner 1+2 als Schnellschuss aus Ranger gebaut kann man dazuz&auml;hlen. Doch das wich dann sorgf&auml;ltig vorbereiteten Missionen, die auch wesentlich erfolgreicher waren. Russland behielt das Streben unbedingt Erster zu sein bis 1973 bei. Bedingt durch zahlreiche Ausf&auml;lle von Sonden und dem Erfolg der Amis machte man dann oft den zweiten Schritt vor dem Ersten &#8211; obwohl keine russische Sonde erfolgreich den Mars erreicht hatte, plante man mit Mars 2+3 gleich einen Orbiter und die Landung. Eine dritte Sonde sollte die ben&ouml;tigten Daten &uuml;ber Position des Mars und Atmosph&auml;re liefern, die man f&uuml;r die weiche Landung ben&ouml;tigte. Nat&uuml;rlich ging eben diese (nach <a href=\"https:\/\/www.bernd-leitenberger.de\/murphys-gesetz.shtml\">Murphys Gesetz<\/a>) verloren. So erreichten nur die Orbiter einen Orbit, davon einer einen unplanm&auml;&szlig;igen.<\/p>\n<p>Noch verr&uuml;ckter war es 1974. Diesmal flog gleich eine Armada zum Mars: je zwei Orbiter und zwei Lander. Nur hatte man vier Monate vor dem Start entdeckt, dass Transistoren im Stromverteilungssubsystem ausfielen. Eine Nachfrage bei der Fabrik ergab, dass man dort vor zwei Jahren die Produktion umgestellt hatte: Kontakte waren aus Alu anstatt Gold um Kosten zu sparen. Etwa 1,5 bis 2 Jahre nach Herstellung w&uuml;rden durch interkristalline Korrosion sich die Ausf&auml;lle h&auml;ufen. Das Stromversorgungssystem war \u201egef&uuml;llt\u201c mit den Transistoren. Man errechnete, dass es nur eine 50% Wahrscheinlichkeit gab, dass auch nur eine Raumsonde heil den Mars erreichte. Daher pl&auml;dierte man f&uuml;r eine Verschiebung des Starts um zwei Jahre, doch dann w&auml;ren die Sonden zeitgleich mit Viking gestartet, mit dessen ambitionierten Messprogramm konnte man nicht mithalten. Also wurde von oben befohlen, die Sonden 1973 zu starten. So kam es, wie es kommen sollte. Nur ein Orbiter erreichte en Mars funktionsf&auml;hig. Ein Lander lieferte zwar einige Atmosph&auml;rendaten zerschellet aber bei der Landung..<\/p>\n<p>Die einzige Ausnahme war die Erforschung der Venus. Da hier die USA nach Mariner 5 kein Interesse mehr hatte, konnte man hier eine Mission, auf der letzten aufbauend, Erfolge bei den Landungen erzielen. Allerdings waren hier die Bedingungen auch g&uuml;nstig. Der enorme R&uuml;ckschritt in der Elektronik spielte keine Rolle, wenn eine Sonde nur eine Stunde lang arbeitete und so praktisch nur ein festes Programm abarbeiten konnte.<\/p>\n<p>Die negative Seite der Medaille ist das es in Russland niemals so was wie ein Forschungsprogramm in der Raumfahrt gab. Es gab viele milit&auml;rische Satelliten, dazu kamen Anwendungssatelliten f&uuml;r die Wettervorhersage oder Kommunikation. Aber die Zahl der Forschungssatelliten kann man an den H&auml;nden abz&auml;hlen. Wie auch, da konnte man ja selten Erstleistungen vollbringen, weil die USA sehr bald begannen, Forschungssatelliten f&uuml;r verschiedenste Untersuchungen der Erde, des Weltraums oder des Kosmos zu entwickeln. Zudem wurde das in der &Ouml;ffentlichkeit kaum verfolgt. Ich glaube allerdings nicht das sich daran was ge&auml;ndert h&auml;tte w&auml;re Russland beim Wettlauf Zweiter gewesen. Man muss nur auf China sehen. Die haben jahrelang auch nur milit&auml;rische und anwendungsorientierte Raumfahrt betrieben. Erst in den letzten Jahren haben sie auch begonnen, Forschungsmissionen zu entwickeln. In Russland hatte das Milit&auml;r zu viel Macht. Alle Starts wurden von den Raketenstreitkr&auml;ften durchgef&uuml;hrt. Was nicht irgendwie milit&auml;risch n&uuml;tzlich war, wurde nicht genehmigt. Selbst die <a href=\"https:\/\/www.bernd-leitenberger.de\/proton.shtml\">Proton<\/a> war mal eine ICBM mit 25 t Nutzlast f&uuml;r eine riesige H-Bombe. Selbst das Mondprogramm, von der F&uuml;hrung politisch gewollt hatte damit zu k&auml;mpfen und immer zu wenige Mittel. Der Ausfall der Sonden ist so auch nicht so verst&auml;ndlich. Die meisten Projekte wurden schnell durchgezogen, meist in weniger als zwei Jahren und gemessen an der Gr&ouml;&szlig;e mit geringen Mitteln. Zwar ist es schwierig, den Rubel in US-Dollar umzurechnen, doch selbst bei den h&ouml;heren Umrechnungskursen kommt man auf erschreckend niedrige Zahlen. <a href=\"https:\/\/www.bernd-leitenberger.de\/phobos.shtml\">Phobos 1+2 <\/a>sollen 200 Millionen Pfund, damals etwa 300 Millionen Dollar gekostet haben. Das war in etwa ein Drittel dessen, was der Mars Observer kostete \u2013 mit weniger Experimenten ohne Landesonden und als Einzelsonde. Russland machte schon 30 Jahre vor der NASA die Urerfahrung: <a href=\"https:\/\/www.bernd-leitenberger.de\/faster-better-cheaper.shtml\">Faster, Cheaper und Better<\/a> geht nicht. Es sind immer nur zwei Ziele umsetzbar. Beide Mal blieb das \u201eBetter\u201c auf der Strecke&#8230;<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/vg01.met.vgwort.de\/na\/129c5170f93f416e9e5be4dfad1bb1e1\" alt=\"\" width=\"1\" height=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kommen nun heute und morgen. Zuerst einmal ist das der 75-ste Jahrestag des ersten erfolgreichen Starts einer A-4 am 3.10.1942. Dann morgen, am 4.10. der 60-ste Jahrestag des Starts von Sputnik 1. Viel ist zu beiden geschrieben worden. Schwer ist es da noch Neues beizutragen, doch ich will es mal probieren. Bei der A-4 wurde [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-12796","post","type-post","status-publish","format-standard","hentry","category-raumfahrt","entry"],"a3_pvc":{"activated":false,"total_views":1085,"today_views":0},"jetpack-related-posts":[{"id":14020,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2019\/06\/15\/was-waere-wenn-es-wernher-von-braun-nicht-gegeben-haette\/","url_meta":{"origin":12796,"position":0},"title":"Was w&auml;re wenn \u2013 es Wernher von Braun nicht gegeben h&auml;tte?","author":"Bernd Leitenberger","date":"15.06.2019","format":false,"excerpt":"In f\u00fcnf Wochen j\u00e4hrt sich das 50-ste Jubil\u00e4um von Apollo 11. Dann laufen wieder viele Dokus \u00fcber den Wettlauf im All und auch wieder welche um Wernher von Braun. Um ihn kommt man ja nicht herum. Denn er hat nicht nur die Saturn V entwickelt, sondern auch die Raketen, die\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/vg02.met.vgwort.de\/na\/208c56f98e0247c0aeecd2575afa1d16","width":350,"height":200},"classes":[]},{"id":18504,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/25\/die-glorreichen-10-satellitenrekorde\/","url_meta":{"origin":12796,"position":1},"title":"Die glorreichen 10 &#8211; Satellitenrekorde","author":"Bernd Leitenberger","date":"25.01.2026","format":false,"excerpt":"Ich denke, es wird mal wieder Zeit f\u00fcr etwas leichte Unterhaltung die etwas Wissen vermittelt. Also einen Blog \u00fcber 10 Rekorde bei Satelliten, die ihr vielleicht noch nicht kennt. Um eines klarzustellen - es geht nur um Satelliten. Raumsonden sind au\u00dfen vor, weil bei ihnen vieles anderes ist, so kann\u2026","rel":"","context":"In &quot;Die Glorreichen 10&quot;","block_context":{"text":"Die Glorreichen 10","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/die-glorreichen-10\/"},"img":{"alt_text":"","src":"\/img\/1kgsats.png","width":350,"height":200,"srcset":"\/img\/1kgsats.png 1x, \/img\/1kgsats.png 1.5x, \/img\/1kgsats.png 2x, \/img\/1kgsats.png 3x"},"classes":[]},{"id":18488,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/16\/die-raumfahrtnachlese-2025\/","url_meta":{"origin":12796,"position":2},"title":"Die Raumfahrtnachlese 2025","author":"Bernd Leitenberger","date":"16.01.2026","format":false,"excerpt":"Ich schiebe etwas sp\u00e4t eine kurze Raumfahrtnachlese f\u00fcr 2025 nach. Das auff\u00e4lligste ist nat\u00fcrlich der rasante Anstieg der Starts bzw. Startversuche, 325 waren es letztes Jahr. Eine Steigerung um 58 gegen\u00fcber letztem Jahr und damit nicht nur in der H\u00f6he ein Rekord, sondern auch im Zuwachs. Nur mal als Vergleich\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/25bb1cf6b21949af835bc77482e531d6","width":350,"height":200},"classes":[]},{"id":18469,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/11\/13\/operation-fishbowl\/","url_meta":{"origin":12796,"position":3},"title":"Operation Fishbowl","author":"Bernd Leitenberger","date":"13.11.2025","format":false,"excerpt":"Hallo, ich schreibe weiter an meinem Buch, die Auskopplung der Thor und Delta aus dem Buch \u00fcber die US-Tr\u00e4gerraketen. Und wie immer nutze ich die Zeit noch was zu erg\u00e4nzen. Seitens des Einsatzes der Thor bzw. Delta als Satellitentr\u00e4ger gibt es wenig Neues zu schreiben da habe ich schon beim\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg","width":350,"height":200,"srcset":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1.5x"},"classes":[]},{"id":18515,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/30\/thor-agena-a-und-kh-1\/","url_meta":{"origin":12796,"position":4},"title":"Thor Agena A und KH-1","author":"Bernd Leitenberger","date":"30.01.2026","format":false,"excerpt":"Heute gibt es wieder als Blog-Artikel einen kleinen Auszug aus dem aktuellen Buchmanuskript. Diesmal der Artikel \u00fcber die Thor Agena A, eine der fr\u00fchen Versionen die nicht oft flog. Der Artikel ist trotzdem l\u00e4nger geworden, weil eine der Neuerung, die ich beim laufenden Manuskript eingef\u00fchrt habe, ist das ich auch\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/8002b5135f8349af8dcfab89af02a721","width":350,"height":200},"classes":[]},{"id":18480,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/12\/27\/die-umweltbilanz-der-new-shepard\/","url_meta":{"origin":12796,"position":5},"title":"Die Umweltbilanz der New Shepard","author":"Bernd Leitenberger","date":"27.12.2025","format":false,"excerpt":"K\u00fcrzlich ist die deutsche Michaela Benthaus mit Blue Origin auf der Mission New Shepard NS37 geflogen. Da die Dame querschnittsgel\u00e4hmt ist, war dies den Nachrichten eine Schlagzeile wert, \u00e4hnlich wie vor einigen Monaten der Flug von Kate Perry, ebenfalls mit Blue Origin auf der New Shepard. Was dabei untergegangen ist,\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg04.met.vgwort.de\/na\/99ff84c04ca842a2baa1d4552eb54bab","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/12796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=12796"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/12796\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=12796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=12796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=12796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}