{"id":15787,"date":"2022-02-21T11:12:45","date_gmt":"2022-02-21T10:12:45","guid":{"rendered":"https:\/\/www.bernd-leitenberger.de\/blog\/?p=15787"},"modified":"2022-02-21T11:12:45","modified_gmt":"2022-02-21T10:12:45","slug":"heimische-superfoods-wasserloesliche-vitamine","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2022\/02\/21\/heimische-superfoods-wasserloesliche-vitamine\/","title":{"rendered":"Heimische Superfoods \u2013 Wasserl&ouml;sliche Vitamine"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_15787\" class=\"pvc_stats all  \" data-element-id=\"15787\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Heute nun zu dem zweiten Teil der heimischen Superfoods. Wer den <a href=\"https:\/\/www.bernd-leitenberger.de\/blog\/2022\/02\/20\/heimische-superfoods-fettloesliche-vitamine\/\">ersten Teil mit den fettl&ouml;slichen Vitaminen<\/a> verpasst hat, kann ihn ja noch nachlesen. Dort ist auch der einleitende Teil, weshalb ich von \u201eSuperfoods\u201c spreche wichtig, den wiederhole ich hier nicht komplett. Aber das wichtigste: F&uuml;r die Einstufung als \u201eSuperfood\u201c gilt: Meine Definition von \u201eSuperfood\u201c ist, dass das entsprechende Lebensmittel deutlich mehr eines Inhaltsstoffes enth&auml;lt, als der Durchschnitt der Lebensmittel. Das muss sich an einer typischen Verzehrmenge orientieren. Um zwei Beispiele zu nehmen. Kr&auml;uter enthalten oft sehr viele Vitamine und Mineralstoffe, aber wie viel Kr&auml;uter isst man t&auml;glich, verglichen z. B. Mit Obst oder Gem&uuml;se? Es spielt auch der Energiegehalt eine Rolle. So sind Pflanzen&ouml;le reich an fettl&ouml;slichen Vitaminen, aber sie haben auch den h&ouml;chsten Energiegehalt aller Lebensmittel. Demgegen&uuml;ber findet man die Vitamine in kleineren Mengen auch in vielen Gem&uuml;sen, die sind aber viel energie&auml;rmer.<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg09.met.vgwort.de\/na\/580adb4f6dd14240887f1b3b02ad1dfe\" alt=\"\" width=\"1\" height=\"1\" \/><!--more--><\/p>\n<p>Es gibt insgesamt acht wasserl&ouml;sliche Vitamine. Sechs davon fasst man zu der Vitamin B-Gruppe zusammen. Das hat historische Gr&uuml;nde. F&uuml;nf der sechs Vitamine der B-Gruppe sind Coenzyme in Stoffwechselvorg&auml;ngen und wird der gest&ouml;rt, dann &auml;u&szlig;ern sich Probleme zuerst in den Organen die eine hohe Stoffwechselaktivit&auml;t haben. Bei allen Vitaminen gibt es bei M&auml;ngeln neurologische Ausf&auml;lle. Daher nahm man zuerst an, es w&auml;re ein Vitamin. Erst als man die Substanzen identifizieren konnte, wurden daraus mehrere Vitamine, die dann eine Zahl zur Unterscheidung zus&auml;tzlich bekamen.<\/p>\n<h3 class=\"western\">Vitamin B<sub>1<\/sub><\/h3>\n<p>Das Vitamin B<sub>1<\/sub> \u2013 Thiamin ist Coenzym bei dem Enzym Pyruvatdehydrogenase. Dieses Enzym bildet aus dem Abbauprodukt von Glucose und damit allen Kohlenhydraten Actyl-CoA, das in den Zitronens&auml;urezyklus eingeschleust wird. Hat man davon zu wenig, so ist dieser elementare Reaktionsschritt gest&ouml;rt und besonders das Gehirn, das nur aus Glucose Energie gewinnen kann, hat Probleme und es gibt neurologische St&ouml;rungen.<\/p>\n<p>Thiamin gibt es nicht so h&auml;ufig in der Nahrung und die Lebensmittel, die es enthalten, geh&ouml;ren nicht zu den h&auml;ufig verzehrten Nahrungsmitteln. Zudem wird es bei der Nahrungszubereitung leicht zerst&ouml;rt. Daher gilt Vitamin B<sub>1<\/sub> als eines der <a href=\"https:\/\/www.bernd-leitenberger.de\/vitamin.shtml\">Vitamine<\/a>, wo es leichter zu M&auml;ngeln kommen kann als bei anderen.<\/p>\n<p>Relativ reich an Thiamin ist Fleisch, vor allem Schweinefleisch, aber auch H&uuml;hnerfleisch und Rinderfleisch enthalten nennenswerte Mengen an Thiamin. In pflanzlichen Nahrungsmitteln kommt es kaum vor. Ausnahmen sind die &auml;u&szlig;eren Schalen von Getreide, weshalb man es auch in Vollkornprodukten in nennenswerter Menge findet und H&uuml;lsenfr&uuml;chte wie Erbsen, Linsen und Bohnen. In vielen L&auml;ndern, wo der Verzehr von Getreide ohne die &auml;u&szlig;eren Kornschichten dominiert, (Wei&szlig;mehl, polierter Reis) wird dem Mehl Thiamin zugesetzt, nicht jedoch bei uns.<\/p>\n<h3 class=\"western\">Vitamin B<sub>2<\/sub><\/h3>\n<p>Das Vitamin B<sub>2<\/sub> \u2013 Riboflavin ist ebenfalls eine Coenzymvorstufe. Aus ihm werden die Coenzyme FAD und FMN gebildet, die bei Reduktionsprozessen Wasserstoff abgeben und Oxidationsprozessen Wasserstoff abgeben. Diese Coenzyme werden im Zitronens&auml;urezyklus und bei dem Fetts&auml;ureabbau, der <span style=\"font-family: Liberation Serif, serif;\">\u03b2<\/span>-Oxidation eingesetzt um das Kohlenstoffskelett eines bzw. zweier C-Atome zu oxidieren. Es ist umgekehrt auch beim Aufbau von K&ouml;rpersubstanzen beteiligt, nur reduzieren die Coenzyme dann das Kohlenstoffskelett, daher treten bei M&auml;ngeln Wachstumsst&ouml;rungen bei Kindern auf und man nannte es fr&uuml;her auch \u201eWachstumsvitamin\u201c.<\/p>\n<p>Vitamin B<sub>2<\/sub> kommt in der Nahrung weitaus h&auml;ufiger vor als Vitamin B<sub>1<\/sub>. Es ist auch aufgrund seiner leuchtend gelben Farbe und f&uuml;r die Vitamine relativ hohen Best&auml;ndigkeit ein zugelassener Zusatzstoff: Der Farbstoff E101. Ihn findet man z.B. in Puddingpulver um es gelb zu f&auml;rben.<\/p>\n<p>Vitamin B<sub>2<\/sub> kommt in Milch und allen Milchprodukten vor. Aus ihr wurde es zuerst isoliert, weshalb es fr&uuml;her auch Lactoflavin hie&szlig;. In Hering, Makrelen und Seelachs kommen gr&ouml;&szlig;ere Mengen an Vitamin B<sub>2<\/sub> vor, ebenso in fast allen Fleischarten, besonders viel in H&uuml;hnerfleisch. Pflanzliche Lebensmittel enthalten weniger Riboflavin. Gute Quellen sind Vollkornprodukte, Erbsen, Spargel, Rosenkohl und Spinat.<\/p>\n<h3 class=\"western\">Niacin<\/h3>\n<p>Es gibt einige Vitamine, die haben keine Bezeichnung als \u201e<a href=\"https:\/\/www.bernd-leitenberger.de\/vitaminfragen.shtml\">Vitamin XX<\/a>\u201c, auch wenn man fr&uuml;her zu Niacin auch \u201eVitamin B3\u201c sagte, zumindest da wo man noch mit \u201eVitamin\u201c werben kann ist die Bezeichnung auch heute noch g&auml;ngig. Niacin ist eines der &auml;ltesten bekannten Vitamine und der chemische Name \u201eNikotins&auml;ure\u201c sagt auch warum: es wurde bei der Oxidation von Nicotin entdeckt. Einer der wenigen F&auml;lle wo aus einem t&ouml;dlichen Gift ein lebensnotwendiger Stoff wird. Niacin ist Bestandteil der Koenzyme NADH und NADPH. &Auml;hnlich wie FAD (Riboflavin) transferieren diese Koenzyme Wasserstoff zwischen Molek&uuml;len. Sie k&ouml;nnen so Biomolek&uuml;le oxidieren oder reduzieren. Die Oxidation findet man beim Zitronens&auml;urezyklus und der <span style=\"font-family: Liberation Serif, serif;\">Oxidation<\/span>, die Reduktion beim Aufbau von K&ouml;rpersubstanz z.B. bei der Fetts&auml;uresynthese.<\/p>\n<p>Niacin kommt in vielen Nahrungsmitteln in gr&ouml;&szlig;erer Menge vor, sodass es als unproblematisches Vitamin gilt. Viele Fischarten, alle Arten von Fleisch egal von welchem Tier enthalten reichlich Niacin. In pflanzlichen Lebensmitteln ist es selten, hier in nennenswerten Mengen im Vollkorn, Champignons und Pfifferlingen.<\/p>\n<h3 class=\"western\">Fols&auml;ure<\/h3>\n<p>Die Fols&auml;ure \u2013 so benannt, weil man sie zuerst in Bl&auml;ttern entdeckte \u2013 ist ebenfalls ein Vitamin ohne explizite Bezeichnung, auch wenn manche von Vitamin B<sub>9<\/sub>, Vitamin M oder Vitamin B<sub>11<\/sub> sprechen \u2013 das es drei Bezeichnungen f&uuml;r ein und dieselbe Substanz sind, zeigt schon, das sich keine durchsetzen konnte.<\/p>\n<p>Fols&auml;ure ist als Coenzym beteiligt beim Transfer von Kohlenstoffatomen. Damit nimmt es (mit zwei anderen Vitaminen die Kohlenstoffatome anderer Oxidationsstufen transferieren) eine zentrale Rolle im Stoffwechsel ein. So werden die Purinbasen mithilfe dieses Coenzyms gebildet, aber auch Stoffwechselprodukte abgebaut und umgebaut.<\/p>\n<p>Wie der Name schon andeutet, findet man die Fols&auml;ure vor allem in Gem&uuml;se, von denen man Bl&auml;tter verzehrt oder die zumindest gr&uuml;n sind. Brokkoli, Spinat und Endivien enthalten sehr viel Fols&auml;ure, 100 g decken hier schon den Tagesbedarf. Man findet es aber auch in vielen anderen Gem&uuml;sen und einigen Obstsorten wie Kohlarten, Bananen und Orangen. Kleine Mengen findet man in Rinderfleisch, Vollkornbrot und Erbsen.<\/p>\n<h3 class=\"western\">Pantothens&auml;ure<\/h3>\n<p>Auch bei der Pantothens&auml;ure ist der Name informativ. Man findet sie n&auml;mlich in vielen Nahrungsmitteln (panthos = &uuml;berall). Die Pantothens&auml;ure ist Bestandteil des Coenzym-A mit dem Nach der Glykolyse die Bruchst&uuml;cke der Kohlenhydrate zur Opxidation in den Zitronens&auml;urezyklus eingeschleust werden. Eine &auml;hnliche Funktion hat es bei Fetts&auml;ureabbau und der Fetts&auml;uresynthese. In allen F&auml;llen transportiert es einen Essigs&auml;urerest. Aufgrund der besonderen Bedeutung bei dem Aufbau der Schleimh&auml;ute und der Epithelzellen der Haut wird die Vorstufe der Pantothens&auml;ure, der Alkohol Panthenol auch Hautpflegeprodukten zugesetzt. Der veraltete Namen f&uuml;r die Pantothens&auml;ure ist Vitamin B<sub>5<\/sub>.<\/p>\n<p>Wie schon gesagt kommt die Pantothens&auml;ure in vielen Lebensmitteln vor, in keinem aber in sehr gro&szlig;er Menge. Typisch wird bei den meisten Lebensmitteln mit einer normalen Portion der Bedarf zu 10 bis 20 Prozent gedeckt so findet man die Pantothens&auml;ure in Fleisch (Huhn, Truthahn. Kalb, Rind), in Brot (auch in Wei&szlig;brot), H&uuml;lsenfr&uuml;chten (Erbsen, Sojabohne, Mungobohne), Gem&uuml;se (Spargel, Brokkoli, Blumenkohl) in Pilzen (Champignons) und Obst. Gemessen an dem Energiegehalt ist hier die Wassermelone mit einer Bedarfsdeckung von 20 % beim Verzehr con 100 g das beste Lebensmittel.<\/p>\n<h3 class=\"western\">Vitamin B<sub>6<\/sub><\/h3>\n<p>Das Vitamin B6 besteht aus drei eng miteinander verwandten Biomolek&uuml;len. Alle drei sind gleich aktiv und k&ouml;nnen ineinander umgewandelt werden und werden als Pyridoxin bezeichnet.. Es ist als Coenzym in sehr vielen \u2013 180 \u2013 Enzymen vorhanden, die meisten davon sind im Eiwei&szlig;stoffwechsel aktiv. Sehr oft wird es in der Form von Pyridoxalphophat als Coenzym eingesetzt. M&auml;ngel &auml;u&szlig;ern sich daher zuerst in einem gest&ouml;rten Eiwei&szlig;stoffwechsel. Betroffen ist dann die Haut bei denen die Zellen laufend erneuert werden m&uuml;ssen und die Nervenleitung (Senisbilit&auml;tsst&ouml;rungen) da eine Aufgabe auch die Bildung des Neurotransmitters Serotonin ist.<\/p>\n<p>Aufgrund der Funktion beim Eiwei&szlig;stoffwechsel enthalten Fisch und Fleisch, egal von welcher Tierart relativ viel Pyridoxin. Man findet es aber in gr&ouml;&szlig;ere Menge auch in Vollkorngetreide und daraus hergestellten Produkten. Daneben ist Pyridoxin in Kichererbsen und Linsen zu finden, allen Kohlarten, Kartoffeln und in Bananen.<\/p>\n<h3 class=\"western\">Vitamin B<sub>12<\/sub><\/h3>\n<p>Eine ganz andere Wirkungsweise hat das Vitamin B<sub>12<\/sub>. Es ist ein hochkomplexes Molek&uuml;l von dem man wie vom Vitamin D nur Mikrogrammmengen pro Tag ben&ouml;tigt. Auch hier sind es eine Reihe von Substanzen mit einer variablen Seitenkette die in der Summe als Cobalamine bezeichnet werden. Den Namen hat es weil in seinem Zentrum sich ein Cobalt-Atom befindet, die Struktur &auml;hnelt anderen Biomolek&uuml;len mit einem Metallatom wie dem Chlorophyll (Magnesium als Zentralatom) oder H&auml;moglobin (Eisen als Zentralatom). Vitamin B<sub>12<\/sub> ist nur an zwei Reaktionen beteiligt, die aber eine zentrale Rolle im Organismus spielen. Das Cobalamin &uuml;bertr&auml;gt Methylgruppen von einem Biomolek&uuml;l zum anderen und regeneriert unter anderem auch die Fols&auml;ure die Kohlenstoffatome mit h&ouml;here Oxidationszahl transferiert.<\/p>\n<p>Von einem Mangel betroffen sind vor allem Zellen mit einem hohen Stoffwechselumsatz, das typische Krankheitsbild ist das einer An&auml;mie, bei der die Bildung der roten Blutk&ouml;rperchen gest&ouml;rt ist. Cobalamin wird nur von Mikroorganismen gebildet, weder Pflanzen noch Tiere k&ouml;nnen es bilden. Tiere haben es aber in ihren Zellen als Coenzym und sind so eine wichtige Quelle f&uuml;r das Vitamin B<sub>12<\/sub>, Pflanzen sind weniger stoffwechselaktiv, sie enthalten kaum Cobalamin, weshalb Vegetarier auf die Zufuhr des Vitamins achten m&uuml;ssen. Pflanzliche Nahrungsmittel enthalten nur wesentliche Mengen an Vitamin B<sub>12<\/sub>, wenn sie durch Mikroorganismen verg&auml;rt wurden wie z.\u00a0B. Sauerkraut. Es wird zwar auch von den Darmbakterien produziert, doch deren Produktion scheint f&uuml;r die Bedarfsdeckung nicht auszureichen.<\/p>\n<p>Allerdings kann der K&ouml;rper sehr viel Vitamin B<sub>12<\/sub> speichern. Der k&ouml;rpereigene Speicher soll je nach Literaturquelle zwischen 1 und 5 Jahre ausreichen. Es kann aber nur mit einem im Magen ausgesch&uuml;tteten Protein aufgenommen werden. Menschen ohne Magen bekommen daher regelm&auml;&szlig;ig eine Vorratsinjektion. Gute Vitamin B<sub>12<\/sub> Quellen sind Fische, vor allem der Hering, S&auml;getierfleisch und gereifte K&auml;se wie Emmentaler (hier durch die Mikroorganismen).<\/p>\n<h3 class=\"western\">Vitamin C<\/h3>\n<p>Das Vitamin C ist das wohl bekannteste Vitamin und auch das um das sich die meisten Mythen gebildet haben. Der chemische Name Ascorbins&auml;ure zeigt schon auf das man die Wirkung bei Vitamin C Mangel fr&uuml;h erkannte. Denn es bek&auml;mpft die Skorbut, die Mangelkrankheit bei Ascorbins&auml;uremangel.<\/p>\n<p>Vitamin C ist als wasserl&ouml;sliches Vitamin das Gegenst&uuml;ck zum Vitamin E, es ist ein Radikalf&auml;nger. Daraus lehnten manche ab, das <a href=\"https:\/\/www.bernd-leitenberger.de\/hochdosierte-vitamine.shtml\">Megadosen des Vitamins<\/a> pr&auml;ventiv gegen Krebs helfen sollen. Bewiesen ist dies aber nicht. Daneben hat es eine besondere Funktion im K&ouml;rper, es ist f&uuml;r die Synthese einer Aminos&auml;ure zust&auml;ndig, die im Bindegewebe h&auml;ufig vorkommt. Bei Vitamin C Mangel unterbleibt die Neubildung des Bindegewebes, das &auml;u&szlig;ert sich in Hautekzemen und das Zahnfleisch weicht zur&uuml;ck und die Z&auml;hne fallen aus. Darunter litten jahrhundertelang die Seeleute, die nach Verlassen des Hafens Monate lang keine frischen Lebensmittel mehr bekamen.<\/p>\n<p>Zu den Mythen geh&ouml;rt auch, das Ascorbins&auml;ure bei Erk&auml;ltungen helfen soll, nach Untersuchungen ist das nicht der Fall, allerdings verringert ein hoher Ascorbins&auml;urespiegel einen schweren Verlauf bei einer Erk&auml;ltung.<\/p>\n<p>Vitamin C kommt nur in pflanzlichen Lebensmitteln vor, besonders h&auml;ufig in Obst. Besonders viel in Sanddornbeeren und Azerolas bei denen 100 g ausreichen um den K&ouml;rper f&uuml;r eine bis zwei Wochen mit dem Vitamin zu versorgen. Aber auch Paprika, Erdbeeren, Johannisbeeren und Orangen enthalten viel Vitamin C. Mittlere Gehalte enthalten alle Kohlsorten und Kartoffeln, die durch den regelm&auml;&szlig;igen Konsum aber die gr&ouml;&szlig;te Rolle bei der Bedarfsdeckung spielen.<\/p>\n<p>Das Vitamin C ist durch seine reduktiven Eigenschaften zugelassener Zusatzstoff. Es wird eingesetzt um Lebensmittel vor Oxidationen oder Farbver&auml;nderungen zu sch&uuml;tzen. Bei der Wurstherstellung wird es als mildes Umr&ouml;tungshilfsmittel eingesetzt, das aus Nitrat das eigentlich wirksame Nitrit bildet.<\/p>\n<h3 class=\"western\">Vitamin H<\/h3>\n<p>Das Biotin, so der chemische Name des <a href=\"https:\/\/www.bernd-leitenberger.de\/biotin.shtml\">Vitamin H<\/a> geh&ouml;rt eigentlich zur Vitamin-B-Gruppe, da es wie die Fols&auml;ure und das Cobalamin C-Atome zwischen Molek&uuml;len transferiert, hier den Kohlenstoff in der h&ouml;chsten Oxidationsstufe als Carboxylgruppe. Es bildet so eine Gruppe von Enzymen die Carboxylasen, die im Eiwei&szlig;- und Fetts&auml;urestoffwechsel wichtig sind. Die Bezeichnung \u201eVitamin H\u201c bekam es, weil man zuerst entdeckte das sie es die Mangelerkrankung, schuppigen Hautver&auml;nderungen, bek&auml;mpft. Sodass es den Buchstaben \u201eH\u201c von Haut bekam. Heute wird es auch als Vitamin B<sub>7<\/sub> bezeichnet. Ich rate aber generell dazu im Internet immer nach den eindeutigen chemischen Bezeichnungen zu suchen.<\/p>\n<p>Ein Biotinmangel ist aber selten, auch der Bedarf ist nicht genau bekannt, liegt aber im unteren Mikrogrammbereich. Man geht heute davon aus, dass alleine die Darmbakterien gen&uuml;gend Vitamin H produzieren, auch wenn es in wenigen Lebensmitteln in gr&ouml;&szlig;ere Menge vorkommt (Niere und Leber von S&auml;ugetieren, Erbsen, Champignons). Ein Mangel kann durch St&ouml;rung der Darmflora, Kurzdarm oder den Genuss roher Eier entstehen (enthalten ein Protein das Vitamin H bindet).<\/p>\n<h2 class=\"western\">Die Superfoods<\/h2>\n<p>Err aufgepasst hat wird feststellen das eine Lebensmittel h&auml;ufig genannt werden. Klammert man Leber als Speicherorgan f&uuml;r die meisten Vitamine aus \u2013 sie speichert auch Schwermetalle und soll daher nicht zu h&auml;ufig verzehrt werden, so tauchen sehr oft in den Listen Kohlarten, H&uuml;lsenfr&uuml;chte und als absolutes Superfood Champignons auf. Champignons enthalten vor allem bezogen auf die geringe Energiemenge, die sie liefern sehr viele Vitamine. Das gilt aber auch f&uuml;pr andere Pilze wie Pfifferlinge und Steinpilze.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_15787\" class=\"pvc_stats all  \" data-element-id=\"15787\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>Heute nun zu dem zweiten Teil der heimischen Superfoods. Wer den ersten Teil mit den fettl&ouml;slichen Vitaminen verpasst hat, kann ihn ja noch nachlesen. Dort ist auch der einleitende Teil, weshalb ich von \u201eSuperfoods\u201c spreche wichtig, den wiederhole ich hier nicht komplett. Aber das wichtigste: F&uuml;r die Einstufung als \u201eSuperfood\u201c gilt: Meine Definition von \u201eSuperfood\u201c [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[4815,4816,4813,2921,4814,345,327,334],"class_list":["post-15787","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-folsaeure","tag-panthotensaeure","tag-vitamin-b1","tag-vitamin-b12","tag-vitamin-b2","tag-vitamin-b6","tag-vitamin-c","tag-vitamin-h","entry"],"a3_pvc":{"activated":true,"total_views":5554,"today_views":0},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":12013,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2016\/09\/27\/entstehung-von-leben-auf-der-erde-und-im-sonnensystem\/","url_meta":{"origin":15787,"position":0},"title":"Entstehung von Leben auf der Erde und im Sonnensystem","author":"Bernd Leitenberger","date":"27. September 2016","format":false,"excerpt":"Eines der Dauerbrennerthemen bei Sendungen \u00fcber Astronomie ist es, wo es noch Leben geben k\u00f6nnte. Man kann ja viel spekulieren \u00fcber fremde Planeten, doch am meisten wird nat\u00fcrlich \u00fcber Leben in unserem Sonnensystem spekuliert. Die NASA n\u00e4hrt das sehr gut, vor allem beim Mars. Auch wenn sie von \"Der Suche\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"http:\/\/vg02.met.vgwort.de\/na\/4e11b05707214a29aee07687a953aec8","width":350,"height":200},"classes":[]},{"id":18436,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/11\/intransparenz-bei-omega-3-praeparaten\/","url_meta":{"origin":15787,"position":1},"title":"Intransparenz bei Omega-3 Pr&auml;paraten","author":"Bernd Leitenberger","date":"11. Oktober 2025","format":false,"excerpt":"Ich habe schon ein paar Mal \u00fcber die Omega-3-Fetts\u00e4uren geschrieben. Diesmal m\u00f6chte ich mich relativ kurz fassen und nur auf einen besonderen Aspekt eingehen, n\u00e4mlich den Gehalt an Omega-3-Fetts\u00e4uren in k\u00e4uflichen Pr\u00e4paraten. Aber zuerst ein paar Grundlagen. In der organischen Chemie gibt es ein Nomenklatursystem, um Chemikalien und Substanzen genau\u2026","rel":"","context":"In &quot;Ern\u00e4hrung&quot;","block_context":{"text":"Ern\u00e4hrung","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/ernaehrung\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/c87d2dda0f864e3e9949f7cb7c09df0d","width":350,"height":200},"classes":[]},{"id":5216,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2011\/08\/10\/fcea2\/","url_meta":{"origin":15787,"position":2},"title":"FCEA2","author":"Bernd Leitenberger","date":"10. August 2011","format":false,"excerpt":"CEA2 (Chemical Equilibrium with Applications) ist ein seit gut 30 Jahren entwickeltes NASA Programm mit dem verschiedenste Probleme bei Gasphasen berechnet werden k\u00f6nnen. Ich beschr\u00e4nke mich auf das, was Raumfahrtliebhaber wohl am meisten machen: Die Berechnung der Performance von Triebwerken bei Raketen. Ich will die Benutzung des Programmes einmal erl\u00e4utern,\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/89efc24160614a1a93d97d19447e81a6","width":350,"height":200},"classes":[]},{"id":18385,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/09\/07\/spacex-splitter\/","url_meta":{"origin":15787,"position":3},"title":"SpaceX-Splitter","author":"Bernd Leitenberger","date":"7. September 2025","format":false,"excerpt":"Der heutige Blog ist nicht neu, das, was ich schreibe habe ich schon einige Male geschrieben, aber ebenso wie ich zum wiederholten Male Artikel \u00fcber den Fortschritt oder fehlenden Fortschritt in anderen Webseiten lese, denke ich kann man einiges noch mal aufkochen. Ich will das als eine Folge von fiktiven\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg02.met.vgwort.de\/na\/b2e94ef07fec4d7190886846bcbb4589","width":350,"height":200},"classes":[]},{"id":18442,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/15\/das-v4-wirds-schon-richten\/","url_meta":{"origin":15787,"position":4},"title":"Das V4 wirds schon richten (1)","author":"Bernd Leitenberger","date":"15. Oktober 2025","format":false,"excerpt":"Am 27. August hat der CEO und Technische vision\u00e4r von SpaceX Elon Musk: Eine neue Version des Starships angek\u00fcndigt, das Starship V4. Die wesentlichen Details hat er in einer Folie weiterverbreitet, die ich hier wiedergebe. Ich habe sie zur besseren Lesbarkeit invertiert, das hei\u00dft, die Folie war urspr\u00fcnglich in Schwarz\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"\/img\/starshipv4.jpg","width":350,"height":200,"srcset":"\/img\/starshipv4.jpg 1x, \/img\/starshipv4.jpg 1.5x, \/img\/starshipv4.jpg 2x"},"classes":[]},{"id":18002,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/03\/07\/nachlese-achter-teststart-starship-itf-8\/","url_meta":{"origin":15787,"position":5},"title":"Nachlese achter Teststart Starship ITF-8","author":"Bernd Leitenberger","date":"7. M\u00e4rz 2025","format":false,"excerpt":"Ich mache diese Nachlese wie die bei ITF-7 nicht mehr so ausf\u00fchrlich wie die vorherigen, sondern konzentriere mich auf die wesentlichen Ereignisse. Hier die wesentlichen Ereignisse der Super-Heavy. Bei ihr fielen beim Boostback-Burn zwei der 13 inneren Triebwerke aus. So ist der erste Brennschluss (nach dem nur noch die innersten\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg05.met.vgwort.de\/na\/4424715e8bf74a938ee3b9b549d02a5b","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/15787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=15787"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/15787\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=15787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=15787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=15787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}