{"id":16384,"date":"2023-02-15T00:01:47","date_gmt":"2023-02-14T23:01:47","guid":{"rendered":"https:\/\/www.bernd-leitenberger.de\/blog\/?p=16384"},"modified":"2023-02-15T10:23:45","modified_gmt":"2023-02-15T09:23:45","slug":"die-februar-2023-nachlese-zu-spacex-teil-2","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2023\/02\/15\/die-februar-2023-nachlese-zu-spacex-teil-2\/","title":{"rendered":"Die Februar 2023 Nachlese zu SpaceX \u2013 Teil 2"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_16384\" class=\"pvc_stats all  \" data-element-id=\"16384\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>So nun geht es weiter. Ich schlie&szlig;e nun direkt an den <a href=\"https:\/\/www.bernd-leitenberger.de\/blog\/2023\/02\/14\/die-februar-nachlese-zu-spacex-teil-1\/\">ersten Teil von gestern an<\/a>.<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg05.met.vgwort.de\/na\/6691ddad83e9488e854e59c8cf08627c\" alt=\"\" width=\"1\" height=\"1\" \/><br \/>\nDas zweite Ereignis war der erste <a href=\"https:\/\/spacenews.com\/spacex-performs-starship-static-fire-test\/\">Probestart eines Superboosters<\/a>. Wie immer bei SpaceX gibt es zwei Versionen des Ereignisses. Die Triebwerke liefen 15 Sekunden lang und wurden bei Erreichen des halben Maximalschubs abgeschaltet. Das ist n&ouml;tig, weil es keinen Teststand gibt der mit diesem Schub fertig wird, w&uuml;rden sie vollen Schub erreichen, so w&uuml;rde die Rakete abheben, au&szlig;er SpaceX hat ein Fixierungssystem entwickelt das diesem Schub von 7600 t standh&auml;lt. Dagegen spricht aber das vorzeitige Abschalten vor Erreichen des 100 Prozent Schublevels.<!--more--><\/p>\n<p>Anders als bei einem vorherigen Test explodierte diesmal nichts. Aber es waren nur 31 Triebwerke die arbeiteten. Warum nur 31? Zwei Triebwerke hatten sich schon vorher abgeschaltet! Musk meinte, dass man mit den restlichen Triebwerken schon noch einen Orbit erreicht, aber das ist nur ein Teil der Wahrheit. Zwei Triebwerke bedeuten weniger Schub, weniger Schub bedeutet h&ouml;here Gravitationsverluste und weniger Treibstoffkonsum, die Brennzeit erh&ouml;ht sich als Beispiel f&uuml;r die zweite Simulation die f&uuml;r die wahrscheinlicheren Werte steht, von 156 auf 166 Sekunden. 10 Sekunden lang kann die Gravitation also bei der ersten Stufe die Geschwindigkeit verringern. F&uuml;r den optimalen Fall der Wiederverwendung sinkt so die Nutzlast um 6 t ab. Bei R&uuml;ckkehr zum Startplatz wird es deutlich komplexer weil die Rakete nun auch eine andere, nicht optimale Aufstiegsbahn hat. Unber&uuml;cksichtigt ist dabei die entstehende Schubassymmetrie, die man bei der <a href=\"https:\/\/www.bernd-leitenberger.de\/hercules.shtml\">N-1<\/a> so l&ouml;ste, dass man auch gegen&uuml;berliegende Triebwerke abschaltete, was den negativen Effekt verdoppelt. Selbst wenn man dies durch Schwenken der anderen Triebwerke kompensiert, verliert man so mehr weil der Schubvektor nun nicht mehr parallel zum Schwerpunktvektor liegt.<\/p>\n<p>Vor allem, wer sagt denn das es dabei bleibt? Bei Falcon 9 sind in der Vergangenheit etliche Triebwerke im Flug ausgefallen, wenn eines bei der Z&uuml;ndung ausf&auml;llt, startet man dagegen gar nicht erst. Das man diesen Test trotz zweier Ausf&auml;lle machte, zeigt das man bei SpaceX wohl damit rechnete das nicht alle Triebwerke funktionieren. Unzuverl&auml;ssigkeit ist also schon ein Designmerkmal. Was mich pers&ouml;nlich wundert, ist die extrem lange Zeit. 15 Sekunden sind f&uuml;r das Hochlaufen eines Triebwerks lange. LOX\/LH2 Triebwerke, die konstruktionsbedingt langsam hochlaufen, brauchen rund 7 Sekunden. Die Saturn V hatte mit gestaffelt gez&uuml;ndeten Triebwerken und langer Testdauer 8,9 Sekunden von der Z&uuml;ndung bis zum Abheben. Normal sind bei Triebwerken mit Kohlenwasserstoffen eher 3 Sekunden f&uuml;r das Hochlaufen. Aber es kann sein, das man sie eben lange auf dem 50 Prozent Schubniveau lies, um mehr Daten zu gewinnen.<\/p>\n<p>Aber lassen wir das Ding erst mal fliegen. Der Zeitplan ist optimistisch. Gwen Shotwell meinte:<\/p>\n<p>\u201eShotwell, in her conference presentation, suggested Starship might fly 100 or more times before it carries people, although she later told reporters that was more of a goal than a requirement. \u201cI would love to do hundreds before. I think that would be a great goal and it\u2019s quite possible that we could do that,\u201d she said.\u201c<\/p>\n<p>Was hat das mit dem Zeitplan zu tun? Nun das Starship wird ja auch bei der Artemis-3 Mission bemannt eingesetzt, die ist derzeit f&uuml;r 2025 angesetzt, das hei&szlig;t wir sehen 100 Fl&uuml;ge des Starships in zwei Jahren, was bedenkt man, wie viele Jahre SpaceX brauchte um die Falcon 9 Startrate &uuml;ber 50 pro Jahr zu bringen, dann doch optimistisch ist, zumal die Falcon 9 ja seit Jahren unver&auml;ndert fliegt und man beim Starship sicher einiges in den n&auml;chsten zwei Jahren &auml;ndern wird. Bemannt qualifiziert muss es werden und f&uuml;r Artemis-3 muss auch das auftanken funktionieren.<\/p>\n<p>Neues gibt es auch von Starlink Die <a href=\"https:\/\/spacenews.com\/shotwell-ukraine-weaponized-starlink-in-war-against-russia\/\">Ukraine hat Starlink \u201ezur Waffe gemacht\u201c<\/a> indem sie es zur Drohnensteuerung einsetzten. Wundert mich nicht. Ich glaube es gab schon vor einem oder zwei Jahren die Meldung das die Firmware des Terminals offen wie ein Scheunentor ist und das l&auml;dt eben zu Ver&auml;nderungen ein. Immerhin erfahren wir von Musk das Starlink bisher nur Verluste gemacht hat, was Shotwell dann geradegebogen hat, es gab letztes Jahr zumindest ein Quartal ohne Verluste. Dieses Jahr soll Starlink endlich Geld einbringen. Muss es auch, denn 3.000 Satelliten wurden schon gestartet. Im Prinzip machte SpaceX Geld sofern die Zahl der Abonnenten schneller ansteigt als die Satellitenzahl. Aber das ist nur eine Seite der Medaille. Da sich immer mehr Nutzer einen Satelliten teilen, sinkt die <a href=\"https:\/\/www.golem.de\/news\/datenraten-im-satelliteninternet-starlink-im-sinkflug-2301-171146.html\">Datenrate bei Starlink laufend ab<\/a>, in den USA im dritten Quartal 2022 auf 62 Mbit\/s in Deutschland wo es noch weniger Nutzer gibt auf 94 MBit\/s beide Zahlen deutlich unter den versprochenen 100 Mbit\/s. Inzwischen gibt es in den USA eine Fair Use Policiy, also f&uuml;r die 110 Dollar pro Monat darf man nicht mal so viel saugen wie man will. Mal sehen wir das wird wenn erst mal die anderen Netze dazukommen OneWeb steht ja kurz vor der Fertigstellung der ersten Stufe. Mehr Konkurrenz wird sicher die Gewinne nicht erh&ouml;hen.<\/p>\n<p>Den Einschub mit dem Starlink habe ich gemacht weil ich damit die Verbindung zum Starship wieder habe. Denn es ist f&uuml;r alle au&szlig;er SpaceX v&ouml;llig egal ob das Starship 50, 100 oder 250 t Nutzlast hat. Es gibt keine Nutzlasten dieser Gr&ouml;&szlig;e. Keine Firma wird auch welche entwickeln und riskieren, dass sie dann nicht gestartet werden k&ouml;nnen wenn das mit dem Starship nicht funktioniert oder SpaceX bankrott geht. Alle Satelliten werden so entworfen, das sie mindestens von zwei Tr&auml;gern gestartet werden k&ouml;nnen. Das gilt f&uuml;r kommerzielle, zivile und milit&auml;rische Projekte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/spaceflightnow.com\/wp-content\/uploads\/2023\/02\/20230205amazonasnexus.jpg\" width=\"900\" height=\"1200\" \/>Die n&auml;chste gro&szlig;e Begrenzung ist die Gr&ouml;&szlig;e der Nutzlasth&uuml;lle. Sie ist beim Starship 17 m lang und hat 8 m Durchmesser. Vor allem die L&auml;nge ist die Limitation, schaut man sich Bilder von Satelliten vor dem Start an, die sind meist lang und schmal, hier <a href=\"https:\/\/spaceflightnow.com\/wp-content\/uploads\/2023\/02\/20230205amazonasnexus.jpg\">eingef&uuml;gt<\/a> das des letzten Hispasats der auf einer Falcon 9 vor wenigen Tagen startete. Da sind 17 m schon kurz. Ariane 6 wird wie Ariane 5 eine 20 m lange Verkleidung haben. Ich vermute SpaceX will zwei Satelliten nebeneinander anbringen. Bei GTO Nutzlasten ist das noch gangbar. Doch eine Oberstufe, wie die Centaur nimmt Platz in der Verkleidung weg, sodass f&uuml;r Missionen mit h&ouml;herem Energieaufwand man nicht um das Auftanken herum kommt, das auch erst mal funktionieren muss.<\/p>\n<p>Daher mal einen Vergleich: SpaceX hat jetzt ja schon die Falcon Heavy. Die Falcon Heavy bietet die dreifache Nutzlast der Falcon 9 zu nur 50 Prozent Mehrpreis. Warum gibt es keinen Run auf die Falcon Heavy? Weil die Nutzlastverkleidung dieselbe ist. Sie ist einfach zu klein f&uuml;r eine Rakete mit dieser Nutzlast. Sie ist kleiner (13 m lang) als die einer Ariane 5\/6 mit nominell der halben GTO Nutzlast.<\/p>\n<p>Selbst f&uuml;r die SpaceX eigenen Starlinksatelliten die, das sieht man an den Abbildungen, wirklich den ganzen Platz in der Verkleidung ausnutzen ist sie zu klein. Entsprechend wird die Falcon Heavy nur dann eingesetzt, wenn die Nutzlast nicht gr&ouml;&szlig;er als bei der Falcon 9 ist, aber die Geschwindigkeitsanforderung h&ouml;her. Also die USAF nutzt sie f&uuml;r direkte GEO-Starts und die NASA f&uuml;r die Mission zum Asteroiden Psyche und Elemente des Lunar Gateways. Allesamt Missionen die 2 bis 4 km\/s mehr als eine GTO-Bahn erfordern. Berechnet man das Volumen der Nutzlastverkleidung eines Starships, so dieses Volumen 1,87-mal gr&ouml;&szlig;er als das Volumen der Fairing einer Ariane 5 oder 6. Aber die Nutzlast f&uuml;r den LEO des Starships wird 5 bis 7,5-mal h&ouml;her sein, ohne Wiederverwendung steigt das sogar 12,5-mal an. Solange es also keine Anwendung gibt, bei der die Nutzlast zwar viel wiegt aber ein geringes Volumen hat, wird das startf&auml;hig nur einen Bruchteil der maximalen Nutzlast transportieren. Damit konkurriert es aber auch mit anderen Raketen mit nominell viel kleinerer Maximalnutzlast.<\/p>\n<p>Pikantes Detail am Rande. Gerade bei bemannten Projekte \u2013 damit sollen ja mal Siedler zum Mars fliegen \u2013 ist es so, dass Module ein relativ gro&szlig;es Volumen haben, man kann Menschen ja nicht in eine Konservendose packen.<\/p>\n<p>Viel des Erfolgs des Starships wird davon abh&auml;ngen wo sich der Startpreis einpendelt. Musk weckt ja schon gro&szlig;e Erwartungen wenn er von 1 Million Dollar pro Flug spricht, das ist nur wenig mehr als die rund 5.000 t Treibstoff kosten. Auch hier ein Vergleich: Die Falcon 9 existiert. Sie ist in der Masse zu 80 Prozent wiederverwendbar (nur die Oberstufe geht verloren), bei den Triebwerken zu 90 Prozent. Zehnmal klappt die Bergung mindestens, was die Kosten f&uuml;r neue Hardware um 90 Prozent reduziert. Sie kostet 67 Millionen Dollar pro Start bei Wiederverwendung. Die Falcon Heavy als n&auml;chstgr&ouml;&szlig;eres Modell ist zu 89 Prozent beim Gewicht und 95,4 Prozent bei den Triebwerken wiederverwendbar. Sie kostet 96 Millionen Dollar pro Start bei der Wiederverwendung und ist dreimal schwerer als eine Falcon 9. Da f&auml;llt es mir schwer zu glauben das ein Starship, dass nochmals dreimal schwerer ist, daf&uuml;r hundertmal wiederverwendbar ist, nur noch 1 Million kostet. Denn die Einsparung durch Wiederverwendung ist ja klein. 90 Prozent wurden schon erreicht, weitere 9 Prozent kann das Starship erreichen wenn es die Designvorgaben erf&uuml;llt. Ebenso wird ja schon ein Gro&szlig;teil der Hardware wiederverwendet. Auf der anderen Seite ist eine gr&ouml;&szlig;ere Rakete teurer und das Starship hat auch 39 Triebwerke, gegen&uuml;ber 28 bei einer Falcon Heavy. Mich w&uuml;rde es daher wundern wenn man das Starship die Falcon Heavy in den Kosten unterbieten kann. Dann ist das zwar immer noch ein billiges System, aber es ist nicht der Superentwurf, der nun Fl&uuml;ge so billig macht das es ganz neue Anwendungen gibt. Das war &uuml;brigens auch die Falcon 9 nicht, liegt daran das sie zwar etwas billiger ist als Atlas oder Ariane, aber eben nicht so viel, wie man erwarten w&uuml;rde wenn 80 Prozent der Hardware keine neuen Kosten aufwerfen.<\/p>\n<p>SpaceX braucht das Starship weil neue Starlink Satelliten keine 250 bis 320 kg wie die derzeitigen Satelliten wiegen sondern 1,25 t. Dann kann man niemals die 42.000 Satelliten des Endausbaus mit Falcons starten. Selbst das Starship m&uuml;sste bei den projektierten 5 Jahren Betriebszeit pro Satellit 8.400 dieser Starlinksatelliten pro Jahr starten, dauerhaft, nicht nur einmal bis zur Fertigstellung. Das sind bei 100 t Nutzlast rund 105 Starts pro Jahr. Und 105 Starts sind mehr als SpaceX dieses Jahr mit der schon eingefahrenen Falcon 9 Flotte und drei Weltraumbahnh&ouml;fen schafft. F&uuml;r Starlink gibt es ja nur einen Bahnhof der alle diese Starts abfertigen muss. Ich bleibe skeptisch.Es erinnert mich an zahllose Ank&uuml;ndigungen von Musk an, der irgendwie die Bodenhaftung und die realistische Einsch&auml;tzung was m&ouml;glich ist verloren hat.<\/p>\n<p>Ach ja, damit ihr euch von der k&uuml;nstlichen Intelligenz von ChatGPT &uuml;berzeugen k&ouml;nnt habe ich es diesen Text zusammenfassen lassen. Hier das Ergebnis:<\/p>\n<p>&#8222;Der Blog-Beitrag fasst die wichtigsten Ereignisse und Neuigkeiten von SpaceX im Februar 2023 zusammen. Der zweite Teil behandelt unter anderem den erfolgreichen Start und die Landung einer Falcon 9 Rakete, den Testflug des Starship SN11 Prototyps, die Ank&uuml;ndigung von neuen Partnerschaften und Kooperationen und den aktuellen Stand des Starlink Satelliten-Netzwerks.&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_16384\" class=\"pvc_stats all  \" data-element-id=\"16384\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>So nun geht es weiter. Ich schlie&szlig;e nun direkt an den ersten Teil von gestern an. Das zweite Ereignis war der erste Probestart eines Superboosters. Wie immer bei SpaceX gibt es zwei Versionen des Ereignisses. Die Triebwerke liefen 15 Sekunden lang und wurden bei Erreichen des halben Maximalschubs abgeschaltet. Das ist n&ouml;tig, weil es keinen [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4106],"tags":[5,4385],"class_list":["post-16384","post","type-post","status-publish","format-standard","hentry","category-spacex","tag-spacex","tag-starship","entry"],"a3_pvc":{"activated":true,"total_views":1022,"today_views":0},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":17895,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/01\/19\/nachlese-teststart-starship-itf-7\/","url_meta":{"origin":16384,"position":0},"title":"Nachlese Teststart Starship ITF-7","author":"Bernd Leitenberger","date":"19. Januar 2025","format":false,"excerpt":"Die erste Phase lief noch nach Plan. Das Starship mit der Seriennummer S33 und die SuperHeavy mit der Seriennummer B14 hoben mit 37 Minuten Versp\u00e4tung um 4:37 nachmittags lokaler Zeit ab. Der Flug selbst hatte einen genehmigten Startzeitraum von 10. bis zum 17. Januar 2025 mit jeweils einem Startfenster pro\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/60231369830445f0b5712ad7af8fdc7a","width":350,"height":200},"classes":[]},{"id":18002,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/03\/07\/nachlese-achter-teststart-starship-itf-8\/","url_meta":{"origin":16384,"position":1},"title":"Nachlese achter Teststart Starship ITF-8","author":"Bernd Leitenberger","date":"7. M\u00e4rz 2025","format":false,"excerpt":"Ich mache diese Nachlese wie die bei ITF-7 nicht mehr so ausf\u00fchrlich wie die vorherigen, sondern konzentriere mich auf die wesentlichen Ereignisse. Hier die wesentlichen Ereignisse der Super-Heavy. Bei ihr fielen beim Boostback-Burn zwei der 13 inneren Triebwerke aus. So ist der erste Brennschluss (nach dem nur noch die innersten\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg05.met.vgwort.de\/na\/4424715e8bf74a938ee3b9b549d02a5b","width":350,"height":200},"classes":[]},{"id":13317,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2018\/04\/04\/die-aufklaerung-des-aprilscherzes\/","url_meta":{"origin":16384,"position":2},"title":"Die Aufkl&auml;rung des Aprilscherzes","author":"Bernd Leitenberger","date":"4. April 2018","format":false,"excerpt":"So, nun komme ich wieder mal zu einem Blog. Derzeit arbeite ich noch flei\u00dfig an der Aufstiegssimulation, nun vor allem im Pflegen der alten Daten. Rund 200 Tr\u00e4ger wollen schlie\u00dflich erg\u00e4nzt werden. Anscheinend hat es keiner gemerkt: Der letzte Blog war ein Aprilscherz. Nat\u00fcrlich w\u00fcrde unsere Regierung nie auf seinen\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"\/img\/sapcex-falcons.jpg","width":350,"height":200,"srcset":"\/img\/sapcex-falcons.jpg 1x, \/img\/sapcex-falcons.jpg 1.5x, \/img\/sapcex-falcons.jpg 2x"},"classes":[]},{"id":18439,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/14\/nachlese-elfter-teststart-des-starships-ift-11\/","url_meta":{"origin":16384,"position":3},"title":"Nachlese elfter Teststart des Starships IFT-11","author":"Bernd Leitenberger","date":"14. Oktober 2025","format":false,"excerpt":"Die Nachlese zum gestrigen Starship-Start kann ich recht kurz machen, denn diesmal klappte noch mehr als beim letzten Mal. Dauerhaft, zusammen mit dem Artikel f\u00fcr den Flugplan und Abbildungen findet ihr das ganze auch auf der Website. Drei Dinge fielen mir auf: Beim Boostback-Burn der Super Heavy schaltete eines der\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg04.met.vgwort.de\/na\/d237e8ebe33746ddb174f7e072b94b6c","width":350,"height":200},"classes":[]},{"id":18442,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/15\/das-v4-wirds-schon-richten\/","url_meta":{"origin":16384,"position":4},"title":"Das V4 wirds schon richten (1)","author":"Bernd Leitenberger","date":"15. Oktober 2025","format":false,"excerpt":"Am 27. August hat der CEO und Technische vision\u00e4r von SpaceX Elon Musk: Eine neue Version des Starships angek\u00fcndigt, das Starship V4. Die wesentlichen Details hat er in einer Folie weiterverbreitet, die ich hier wiedergebe. Ich habe sie zur besseren Lesbarkeit invertiert, das hei\u00dft, die Folie war urspr\u00fcnglich in Schwarz\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"\/img\/starshipv4.jpg","width":350,"height":200,"srcset":"\/img\/starshipv4.jpg 1x, \/img\/starshipv4.jpg 1.5x, \/img\/starshipv4.jpg 2x"},"classes":[]},{"id":18656,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/05\/09\/vor-dem-12-ten-testflug-des-starships\/","url_meta":{"origin":16384,"position":5},"title":"Vor dem 12-ten Testflug des Starships","author":"Bernd Leitenberger","date":"9. Mai 2026","format":false,"excerpt":"W\u00e4hrend ich f\u00fcr den Artikel recherchiere, gibt es noch keinen Starttermin f\u00fcr das erste Starship V3, der Start wurde mehrfach von M\u00e4rz bis Mai verschoben. SpaceX k\u00fcndet immer kurzfristig an, sodass sich das mit dem Schreiben des Blogs \u00fcberlappen kann. Es ist klar, das mit V3 vieles besser werden muss.\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/dc51ed97a0f548b6bea1f689ca456c33","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/16384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=16384"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/16384\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=16384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=16384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=16384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}