{"id":18250,"date":"2025-06-26T18:34:45","date_gmt":"2025-06-26T16:34:45","guid":{"rendered":"https:\/\/www.bernd-leitenberger.de\/blog\/?p=18250"},"modified":"2025-06-27T06:33:19","modified_gmt":"2025-06-27T04:33:19","slug":"die-schwierige-landung-des-starships-auf-dem-mars","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/06\/26\/die-schwierige-landung-des-starships-auf-dem-mars\/","title":{"rendered":"Die schwierige Landung des Starships auf dem Mars"},"content":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_18250\" class=\"pvc_stats all  \" data-element-id=\"18250\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>W&auml;hrend man bei SpaceX seit nun schon &uuml;ber 20 Jahren den Mars kolonisieren will, so preiswert, dass es sich (fast) jeder Milliard&auml;r leisten kann und das auch innerhalb der n&auml;chsten 2-3 Jahre passiert (und das schon seit 10 Jahren) machen sich andere Gedanken wie man dort hinkommt und heil landet und so auch ich.<!--more--><\/p>\n<h4 class=\"western\">Warum sollte man die Reisezeit reduzieren?<\/h4>\n<p>Also wenn ich mal Langweile ausschlie&szlig;en will &#8211; selbst Orbitaltouristen halten es nicht mal eine Woche in einer Dragon aus, wie die letzten Missionen ohne Kopplung an die ISS zeigen &#8211; gibt es zwei gute Gr&uuml;nde schneller zu reisen:<\/p>\n<p>Grund 1: die Strahlenbelastung. Uns sch&uuml;tzt die Erde vor kosmischen Strahlen. Wenn ich seltene, unvorhersagbare Ereignisse wie einen Gammastrahlenausbruch einer Verschmelzung von Neutronensternen weglasse, gegen die man sich praktisch nicht oder nur mit extrem dicker Abschirmung sch&uuml;tzen kann ist die Hauptquelle der <a href=\"https:\/\/www.bernd-leitenberger.de\/strahlung.shtml\">Strahlenbelastung<\/a> die Sonne. Deren Strahlung ist nicht konstant, sondern schwankt in einem 11-j&auml;hrigen Rhythmus. das solare Maximum wurde gerade passiert, letztes Jahr gab es durch einen Strahlensturm Polarlichter selbst bei uns. W&uuml;rde man in 5 Jahren starten, so w&auml;re das nahe dem Minimum. W&auml;hrend des Maximums ist die Strahlenbelastung allgemein h&ouml;her, es treten aber auch mehr kurzzeitige Ausbr&uuml;che durch Flares auf und diese sind heftiger. Sie sind die eigentliche Gefahr f&uuml;r die Besatzung. Klar eine kurze Reisezeit verringert die Gefahr, aber viel einfacher ist es, nicht rund um das Maximum zu starten. Vor allem sch&uuml;tzt auch der Mars nicht vor den kosmischen Strahlen. Er hat kein Magnetfeld und die Atmosph&auml;re ist zu d&uuml;nn. Direkt nach der Landung w&auml;re bis man Schutzbehausungen unter Gestein gebaut hat, die Belastung am Tag genauso hoch wie w&auml;hrend der Reise zum Mars.<\/p>\n<p>Grund 2: Abbau der Muskelmasse: Nach der Landung m&uuml;ssen die Siedler aussteigen und gleich mit der Arbeit beginnen, das in klobigen Raumanz&uuml;gen. Der Mars hat zwar eine geringere Schwerkraft, aber die Raumanz&uuml;ge &#8211; die schon bei Apollo 84 kg wogen und seitdem schwerer wurden &#8211; gleichen das aus, zudem erfordern sie viel mehr Kraft bei den Bewegungen, weil die dicke Schutzschicht auch bewegt werden muss. Die Muskelmasse nimmt unter Schwerelosigkeit ab und zwar schnell, da spielt es keine Rolle ob man 90 oder 180 Tage unterwegs ist. Dagegen hilft Training, aber nur bedingt. Noch problematischer ist, das bei der Landung die zuk&uuml;nftigen Siedler mit mehr als den 0,4 g die der Mars als Schwerkraft hat belastet werden. Wenn sie da etwas tun m&uuml;ssen, und sei es nur Kn&ouml;pfe dr&uuml;cken, dann ist das &auml;u&szlig;ert schwer.<\/p>\n<h4 class=\"western\">Die Problematik der Route<\/h4>\n<p>Die energiesparendste Route zum Mars sind <a href=\"https:\/\/www.bernd-leitenberger.de\/erreichbarkeit-der-planeten.shtml\">Hohmannbahnen<\/a>. Die Reisedauer auf ihnen h&auml;ngt ab von der Entfernung der Planeten. der Mars hat eine sehr elliptische Umlaufbahn. N&auml;hert er sich auf 207 Millionen km der Sonne so braucht man 237 Tage auf einer Hohmannbahn zum Mars, bei der maximalen Entfernung von 249 Millionen km sind es dagegen 280 Tage. Alle 15 \/ 17 Jahren wiederholen sich jeweils g&uuml;nstige bzw. ung&uuml;nstige Startgelegenheiten. Die Abbildung erstellt mit dem <a href=\"https:\/\/trajbrowser.arc.nasa.gov\/index.php\">NASA Trajectory Browser<\/a> zeigt dies: Die Startgeschwindigkeit f&uuml;r einen Vorbeiflug, der einer Landung vorangeht, schwankt zwischen 3,5 und 4 km\/s relativ zur Erdbahn, und man erkennt die Wiederholung der Fenster alle 15 bzw. 17 Jahre (jeweils im Wechsel, bei der Abbildung: 17 Jahre). Die Reisezeiten schwanken aber viel st&auml;rker als die Geschwindigkeit. Das NASA-Programm liefert f&uuml;r 2018\/2025 eine minimale Dauer von 128 Tagen f&uuml;r die Reise. 2022 \/ 2037 sind es dagegen 304 und 320 Tage. Das hei&szlig;t, wenn ich nur zum richtigen Zeitpunkt starte, kann ich viel Zeit einsparen, und ben&ouml;tige zudem eine geringe Startgeschwindigkeit. Allerdings ist der Preis f&uuml;r schnelle Routen eine hohe Ankunftsgeschwindigkeit: 7,85 und 7,32 km\/s bei den schnellen Routen und 5,52 und 5,58 km\/s bei den langen Routen. Geht man nun zu schnelleren Routen &uuml;ber, so steigt die Ankunftsgeschwindigkeit rasch an. Ideale Hohmannbahnen haben eine solare Geschwindigkeitsdifferenz von unter 4 km\/s. Die solare Geschwindigkeitsdifferenz kommt vektoriell zur Fluchtgeschwindigkeit hinzu, auf die ein fallender K&ouml;rper beschleunigt wird. So kommt man zu obigen (h&ouml;heren) Geschwindigkeiten. Raumsonden haben daher beim Eintritt in die Atmosph&auml;re bisher Geschwindigkeiten von 5,5 bis 7 km\/s gehabt &#8211; eben die oben vom Trajectory Browser angegebene Geschwindigkeiten. Hier mal eine Tabelle, welche Folgen die schnellere Reise hat. Angenommen wird ein Mars in 228 Millionen km Sonnendistanz, also der mittleren Entfernung des Mars von der Sonne:<\/p>\n<table width=\"100%\" cellspacing=\"0\" cellpadding=\"2\">\n<thead>\n<tr valign=\"top\">\n<th width=\"25%\">Reisezeit<\/th>\n<th width=\"25%\">v Start<\/th>\n<th width=\"25%\">v Ankunft solar<\/th>\n<th width=\"25%\">v Ankunft planetar<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr valign=\"top\">\n<td width=\"25%\">259 Tage (Hohmann)<\/td>\n<td width=\"25%\">11,4 km\/s<\/td>\n<td width=\"25%\">2,7 km\/s<\/td>\n<td width=\"25%\">5,7 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">210 Tage<\/td>\n<td width=\"25%\">11,44 km\/s<\/td>\n<td width=\"25%\">3,1 km\/s<\/td>\n<td width=\"25%\">5,9 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">180 Tage<\/td>\n<td width=\"25%\">11,54 km\/s<\/td>\n<td width=\"25%\">4,0 km\/s<\/td>\n<td width=\"25%\">6,4 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">150 Tage<\/td>\n<td width=\"25%\">11,78 km\/s<\/td>\n<td width=\"25%\">5,8 km\/s<\/td>\n<td width=\"25%\">7,7 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">120 Tage<\/td>\n<td width=\"25%\">12,3 km\/s<\/td>\n<td width=\"25%\">9,1 km\/s<\/td>\n<td width=\"25%\">10,4 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">90 Tage<\/td>\n<td width=\"25%\">13,8 km\/s<\/td>\n<td width=\"25%\">15,8 km\/s<\/td>\n<td width=\"25%\">16,6 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">60 Tage<\/td>\n<td width=\"25%\">19,2 km\/s<\/td>\n<td width=\"25%\">17,7 km\/s<\/td>\n<td width=\"25%\">18,4 km\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">30 Tage<\/td>\n<td width=\"25%\">44,9 km\/s<\/td>\n<td width=\"25%\">24,9 km\/s<\/td>\n<td width=\"25%\">25,4 km\/s<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Zu der solaren Geschwindigkeit kommt noch die Beschleunigung durch den Mars. Die planetaren Ankunftsgeschwindigkeiten liegen zwischen 5,7 und 25,4 km\/s. Die Fluchtgeschwindigkeit des Mars von 25 km\u00b2\/s\u00b2 macht bei steigenden Geschwindigkeiten immer weniger an der Gesamtgeschwindigkeit aus. Man sieht: die Startgeschwindigkeit von der Erde steigt zuerst nur langsam an, sehr kurze Routen ben&ouml;tigen aber eine hohe Startgeschwindigkeit. Die Ankunftsgeschwindigkeit steigt dagegen rasch an.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"\/img\/mars-flybay2014-2040.png\" width=\"1232\" height=\"553\" \/><\/p>\n<h4 class=\"western\">Abbremsen?<\/h4>\n<p>Beim Mars kommt nun erst mal die Problematik des Abbremsens. Denn die Marsatmosph&auml;re ist d&uuml;nn, so d&uuml;nn wie in 40 bis 43 km H&ouml;he auf der Erde je nach Temperatur. Ich habe mir mal das Video der Starship Landung 6 angesehen, die ja recht gut verlief. In 42 km H&ouml;he ist es noch 7600 km\/h schnell, das sind 2,1 km\/s. W&auml;re dies der Mars, so m&uuml;sste man 2,1 km\/s abbremsen, wenn man mit derselben Geschwindigkeit ankommt (7,8 km\/s entspricht in etwa der Ankunftsgeschwindigkeit bei 150 Tagen Reisedauer in der obigen Tabelle). Aber der Mars ist nicht die Erde. Seit 2006 umkreist der <a href=\"https:\/\/www.bernd-leitenberger.de\/mro.shtml\">MRO<\/a> den Mars in 320 km H&ouml;he. Auf der Erde w&uuml;rde er sich bei den gro&szlig;en Solarpaneelen gerade mal einige Monate in dieser H&ouml;he halten k&ouml;nnen. Der Treibstoffvorrat reicht aber noch bis 2034. Inklusive Lage&auml;nderungen braucht er nur 10 kg Treibstoff pro Jahr. Auf der Erde m&uuml;sste man ihn in mindestens 520 km H&ouml;he platzieren, also 200 km h&ouml;her. Das zeigt: die Marsatmosph&auml;re ist nicht nur viel d&uuml;nner, ihre Dichte nimmt auch viel schneller ab. Das l&auml;sst nur einen kleinen H&ouml;henbereich zu, in dem ein Starship passiv die Geschwindigkeit abbauen kann. Bei der Erde begann die Verz&ouml;gerung, sobald 105 km H&ouml;he passiert waren, beim Mars bei meiner Simulation erst in 59 bis 64 km H&ouml;he je nach Ankunftsgeschwindigkeit und Masse. Im einen Fall hat man 105 km H&ouml;he und 20 Minuten Zeit (<a href=\"https:\/\/www.bernd-leitenberger.de\/Starship-ITF6.shtml\">IFT-6 Video<\/a>) im anderen Fall ist in meiner Simulation die Oberfl&auml;che in 150 Sekunden erreicht und das Starship ist noch 1,3 km\/s schnell.<\/p>\n<p>Es kommt noch schlimmer: die Restgeschwindigkeit ist stark abh&auml;ngig von der Masse. Ich habe mit 200 t gerechnet, also 100 t Starship und 100 t Nutzlast. Man ben&ouml;tigt aber Treibstoff um die 1,3 km\/s zu vernichten und 100 t Masse ist recht wenig. W&auml;re die Nutzlastsektion so mit Ger&auml;ten gef&uuml;llt wie die ISS, sie w&uuml;rde rund 250 t wiegen und ich w&uuml;rde bei einer Marsmission wo man viel schweres Ger&auml;t und Vorr&auml;te f&uuml;r mindestens 3 Jahre braucht, eher annehmen, dass sie noch schwerer ist. 100 t Zuladung ist aber f&uuml;r das Starship V2 erst mal das Ziel. Das Starship V3 soll 200 t erreichen. Mit 200 t Zuladung steigt die Landegeschwindigkeit auf 2,0 km\/s und daf&uuml;r br&auml;uchte man 230 t Treibstoff um diese Geschwindigkeit abzubauen, welche die Masse weiter erh&ouml;hen und die Landegeschwindigkeit erh&ouml;hen wurden &#8211; eine negative Feedbackschleife.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"\/img\/marsvorbeiflug.png\" width=\"517\" height=\"800\" \/><\/p>\n<p>Man wird also eine Bahn nehmen, die m&ouml;glichst flach ist. Dem sind aber Grenzen gesetzt. Bei IFT-6 lag der erdn&auml;chste Punkt unter der Oberfl&auml;che. Das w&auml;re auch beim Mars m&ouml;glich, ist aber ung&uuml;nstig, denn das f&uuml;hrt zu einem steilen Winkel mit kurzer Abbremsdauer. Ein ganz flacher Winkel ist aber auch schlecht. Die Grafik zeigt die Vorbeiflugbahn am Mars, man sieht jenseits des n&auml;chsten Punktes steigt sie wieder an. Bei einem flachen Winkel wird das Starship nicht gen&uuml;gend abgebremst bevor es wieder ansteigt und verbleibt in einer Sonnenumlaufbahn oder Marsumlaufbahn je nach Abbremsung. Ich habe mit 6 Grad gerechnet, einem typischen Eintrittswinkel bei Apollomissionen.<\/p>\n<h4 class=\"western\">Aktive Abbremsung<\/h4>\n<p>Realistisch wird man also nur bis zu einer bestimmten H&ouml;he passiv abbremsen und dann die Triebwerke z&uuml;nden um die Restgeschwindigkeit zu vernichten. Es gibt hier zwei Optionen:<\/p>\n<p>Wir k&ouml;nnen eine bestimmte Beschleunigung halten oder wir k&ouml;nnen den Maximalschub halten. Der letzte Fall hat die geringere Brenndauer und geringeren Treibstoffverbrauch, f&uuml;hrt aber zu einer hohen Belastung der Besatzung. Das derzeitige Starship hat einen Schub von 15000 kN, das sind bei 300 t Masse und 50 m\/s Startbeschleunigung die noch ansteigt, mehr als beim Start, da werden die Astronauten bewusstlos, nachdem sie monatelang in einer 0 G Umgebung waren. Das geht nur, wenn die Landung voll automatisch ist. Wenn man dagegen mit konstanter Beschleunigung abbremst, kann man die Strecke berechnen, hier f&uuml;r 2 km\/s die vernichtet werden m&uuml;ssen:<\/p>\n<table width=\"100%\" cellspacing=\"0\" cellpadding=\"2\">\n<thead>\n<tr valign=\"top\">\n<th width=\"25%\">Beschleunigung<\/th>\n<th width=\"25%\">Dauer<\/th>\n<th width=\"25%\">Strecke<\/th>\n<th width=\"25%\">Zusatzaufwand<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr valign=\"top\">\n<td width=\"25%\">4 m\/s (Mars Oberfl&auml;chengravitation)<\/td>\n<td width=\"25%\">500 s<\/td>\n<td width=\"25%\">500 km<\/td>\n<td width=\"25%\">2000 m\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">10 m\/s (Erde Oberfl&auml;chengravitation)<\/td>\n<td width=\"25%\">200 s<\/td>\n<td width=\"25%\">200 km<\/td>\n<td width=\"25%\">800 m\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">15 m\/s (Shuttle maximale Belastung bei der Landung)<\/td>\n<td width=\"25%\">133,4 s<\/td>\n<td width=\"25%\">133,4 km<\/td>\n<td width=\"25%\">530 m\/s<\/td>\n<\/tr>\n<tr valign=\"top\">\n<td width=\"25%\">30 m\/s (Shuttle maximale Belastung beim Start)<\/td>\n<td width=\"25%\">66,7 s<\/td>\n<td width=\"25%\">66,7 km<\/td>\n<td width=\"25%\">265 m\/s<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Da ich nicht wei&szlig; wie es bei den derzeitigen Gef&auml;hrten bei der R&uuml;ckkehr ist habe ich das Space Shuttle als Referenz genommen, das war aber f&uuml;r Missionen von maximal 30 Tagen Dauer und damit geringerem Abbau ausgelegt.<\/p>\n<p>Die Strecke ist vektoriell zu sehen, also nicht als H&ouml;he. Bei einem typischen Eintrittswinkel von 6 Grad entfallen von den 2 km\/s nur etwa 200 m\/s f&uuml;r die vertikale Geschwindigkeit, die man zuerst vernichten muss, denn in selbst in 67 Sekunden w&uuml;rde man sonst bei Ber&uuml;cksichtigung der hinzugekommenen Gravitation des Mars um 15 km fallen.<\/p>\n<p>Die letzte Spalte zeigt die Krux: w&auml;hrend die Triebwerke laufen, zieht der Mars mit knapp 4 m\/s weiter an und diese dabei &uuml;ber die Zeit akkumulierte Geschwindigkeit muss man ebenfalls vernichten. Das f&uuml;hrt zu einer Spirale: man braucht mehr Treibstoff, dadurch steigt die Masse an und die Abbremsung durch die Atmosph&auml;re ist geringer, was wiederum zu einer h&ouml;heren Restgeschwindigkeit f&uuml;hrt. Realistisch w&uuml;rde ich daher das zweite Szenario nehmen, schon 50 m\/s Startbeschleunigung w&uuml;rden die Brenndauer auf 40 Sekunden verk&uuml;rzen und die Strecke auf 40 km und den Zusatzaufwand auf 160 m\/s. Leider braucht man selbst dazu dazu 175 t Treibstoff, was die Landgeschwindigkeit auf 3,2 km\/s erh&ouml;ht. Damit braucht man aber noch mehr Treibstoff (obige Rechnung ging von 2 km\/s aus).<\/p>\n<p>Meine Simulation ist rein ballistisch, realistisch hat ein Starship aber einen Auftrieb, der das sinken verlangsamt, die Strecke verl&auml;ngert und damit auch die Landegeschwindigkeit. Aber viel erhoffen sollte man sich davon nicht. Die <a href=\"https:\/\/www.bernd-leitenberger.de\/viking2.shtml\">Viking lander<\/a> hatten eine Masse von 66 kg\/m\u00b2 abbremsende Fl&auml;che. Vor der Fallschirm&ouml;ffnung war er noch knapp 400 m\/s schnell. Ein Starship hat bei 300 t Masse eine Fl&auml;chenbelastung von 667 kg, also mehr das Zehnfache und d&uuml;rfte entsprechend schneller sein wenn die H&ouml;he erreicht wird wo man die Triebwerke z&uuml;ndet. Ich glaube kaum, dass ein Starship auf eine niedrige Geschwindigkeit aerodynamisch abgebremst werden kann &#8211; bei IFT-6 war es in der H&ouml;he die dem Druck beim Mars dem Oberfl&auml;chendruck entspricht, ja auch noch 2,1 km\/s schnell. Bei 2,1 km\/s w&auml;re aber selbst im g&uuml;nstigsten Fall bei 300 t Startmasse die Nutzlast nur noch 50 t schwer. Macht man die Tanks voller, so kommt man in die oben beschriebene Spirale aus immer h&ouml;herer Restgeschwindigkeit, die dann immer mehr Treibstoff n&ouml;tig macht, was wiederum das Gewicht erh&ouml;ht und damit die Restgeschwindigkeit. Es gibt aber immerhin hier eine Obergrenze: Beim Starship V2 passen maximal 1.500 t Treibstoff in den Tanks. Die Nutzlast kann maximal 100 t betragen, bei 100 t Leermasse wiegt das Starship noch etwa 600 t, wenn es die Erdeinflusssph&auml;re verlassen hat, davon 400 t Treibstoff, die die Geschwindigkeit um maximal 3800 m\/s &auml;ndern k&ouml;nnen.<\/p>\n<h4 class=\"western\">Fazit<\/h4>\n<p>Ich glaube, dass man keine realistische Chance hat das Starship weich zu landen. Es ist einfach zu schwer, die Restgeschwindigkeit zu hoch und der Treibstoff denn man daf&uuml;r braucht, erh&ouml;ht die Masse weiter. Aber das ist ehrlich gesagt das kleinste Problem. Bei der Vorgehensweise von SpaceX &#8222;Trial and Error&#8220; haben sie nach neun Starts kein Starship das operativ ist, das zehnte ist k&uuml;rzlich sogar vor dem Start explodiert. Auf der Erde k&ouml;nnen sie jederzeit einen neuen Versuch unternehmen, geplant war nach <a href=\"https:\/\/www.bernd-leitenberger.de\/Starship-ITF9.shtml\">IFT-9<\/a> ja ein Start alle drei bis vier Wochen. Beim Mars w&auml;re ein Fehler noch katastrophaler und da ein Fehler ja systematisch alle Landungen betrifft, w&uuml;rde es auch nicht n&uuml;tzen, pro Startfenster mehrere Starships auf den Weg zu bringen. Wenn sie, wie bei der Erprobung, in den letzten Jahren mindestens 10 Fl&uuml;ge brauchen bis es operativ ist, dann sind das beim Mars 10 Startfenster im Abstand von 26 Monaten, also knapp 22 Jahre. Ob Investoren so lange Geduld haben?<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg02.met.vgwort.de\/na\/95292217cc604a63a6ce7c374ffacbda\" alt=\"\" width=\"1\" height=\"1\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_18250\" class=\"pvc_stats all  \" data-element-id=\"18250\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.bernd-leitenberger.de\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p>W&auml;hrend man bei SpaceX seit nun schon &uuml;ber 20 Jahren den Mars kolonisieren will, so preiswert, dass es sich (fast) jeder Milliard&auml;r leisten kann und das auch innerhalb der n&auml;chsten 2-3 Jahre passiert (und das schon seit 10 Jahren) machen sich andere Gedanken wie man dort hinkommt und heil landet und so auch ich.<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4106],"tags":[994,4385],"class_list":["post-18250","post","type-post","status-publish","format-standard","hentry","category-spacex","tag-bemannte-marslandung","tag-starship","entry"],"a3_pvc":{"activated":true,"total_views":826,"today_views":0},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":13317,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2018\/04\/04\/die-aufklaerung-des-aprilscherzes\/","url_meta":{"origin":18250,"position":0},"title":"Die Aufkl&auml;rung des Aprilscherzes","author":"Bernd Leitenberger","date":"4. April 2018","format":false,"excerpt":"So, nun komme ich wieder mal zu einem Blog. Derzeit arbeite ich noch flei\u00dfig an der Aufstiegssimulation, nun vor allem im Pflegen der alten Daten. Rund 200 Tr\u00e4ger wollen schlie\u00dflich erg\u00e4nzt werden. Anscheinend hat es keiner gemerkt: Der letzte Blog war ein Aprilscherz. Nat\u00fcrlich w\u00fcrde unsere Regierung nie auf seinen\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"\/img\/sapcex-falcons.jpg","width":350,"height":200,"srcset":"\/img\/sapcex-falcons.jpg 1x, \/img\/sapcex-falcons.jpg 1.5x, \/img\/sapcex-falcons.jpg 2x"},"classes":[]},{"id":18385,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/09\/07\/spacex-splitter\/","url_meta":{"origin":18250,"position":1},"title":"SpaceX-Splitter","author":"Bernd Leitenberger","date":"7. September 2025","format":false,"excerpt":"Der heutige Blog ist nicht neu, das, was ich schreibe habe ich schon einige Male geschrieben, aber ebenso wie ich zum wiederholten Male Artikel \u00fcber den Fortschritt oder fehlenden Fortschritt in anderen Webseiten lese, denke ich kann man einiges noch mal aufkochen. Ich will das als eine Folge von fiktiven\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg02.met.vgwort.de\/na\/b2e94ef07fec4d7190886846bcbb4589","width":350,"height":200},"classes":[]},{"id":18709,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/06\/14\/der-blog-wird-20\/","url_meta":{"origin":18250,"position":2},"title":"Der Blog wird 20","author":"Bernd Leitenberger","date":"14. Juni 2026","format":false,"excerpt":"Vor genau 20 Jahren erschien der erste Blog, damals noch unter der Bezeichnung \u201eWeb-Log\u201c. Ich habe gerade einen Artikel gelesen \u00fcber das Zustandekommen des Worts \u201eBlog\u201c. Interessanterweise war es genauso wie bei mir. Obwohl es die Bezeichnung \u201eBlog\u201c damals schon gab, bezeichnete ich meinen Blog lange Zeit als \u201eWeb-Log\u201c, also\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/vg09.met.vgwort.de\/na\/635ab0c6229b4d6898fff3de77fa418a","width":350,"height":200},"classes":[]},{"id":18492,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/18\/spacex-nachlese-2025-und-vorausschau-2026\/","url_meta":{"origin":18250,"position":3},"title":"SpaceX Nachlese 2025 und Vorausschau 2026","author":"Bernd Leitenberger","date":"18. Januar 2026","format":false,"excerpt":"Nach meiner allgemeinen Nachlese nun eine spezielle f\u00fcr SpaceX. Starship Das Starship sah ja schon 2023\/2024 nicht gut aus. Gehen wir mal zur\u00fcck zur Jahreswende 2024\/25: Es gab bis dahin 6 Fl\u00fcge des Starship V1 - auch eine Neuerung des letzten Jahres, denn vorher gab es nur ein \"Starship\", nun\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"\/img\/starship-v4-tabelle.jpg","width":350,"height":200,"srcset":"\/img\/starship-v4-tabelle.jpg 1x, \/img\/starship-v4-tabelle.jpg 1.5x, \/img\/starship-v4-tabelle.jpg 2x"},"classes":[]},{"id":18752,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/07\/10\/tritiumbatterien\/","url_meta":{"origin":18250,"position":4},"title":"&#8222;Tritiumbatterien&#8220;","author":"Bernd Leitenberger","date":"10. Juli 2026","format":false,"excerpt":"Als ich nach dem n\u00e4chsten Starship-Start suchte \u2013 der letzte ist ja schon sieben Wochen her und nach Musk sollten sie ja einmal pro Monat starten fand ich das heutige Thema. Vor allem weil es der erste Start nach dem IPO ist, da ist interessant ob sie da genauso weitermachen\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg08.met.vgwort.de\/na\/6eacf18a864045b598040349a542f226","width":350,"height":200},"classes":[]},{"id":18430,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/06\/treibstoffgewinnung-auf-dem-mars\/","url_meta":{"origin":18250,"position":5},"title":"Treibstoffgewinnung auf dem Mars","author":"Bernd Leitenberger","date":"6. Oktober 2025","format":false,"excerpt":"Bis es eine Kolonie auf dem Mars gibt wird es sicher noch Jahrzehnte dauern, wenn \u00fcberhaupt. Ich bin jetzt 60 und glaube nicht, das ich dies noch erleben werde. Chancen g\u00e4be es f\u00fcr eine Expedition, also einen Flug zum Mars, einen Aufenthalt dort, der aus himmelsmechanischen Gr\u00fcnden etwa eineinhalb Jahre\u2026","rel":"","context":"In &quot;Chemie&quot;","block_context":{"text":"Chemie","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/chemie\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/1098a0be1f3743bcb77eed3bd08301c5","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/18250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=18250"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/18250\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=18250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=18250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=18250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}