{"id":2873,"date":"2010-06-15T01:59:21","date_gmt":"2010-06-14T23:59:21","guid":{"rendered":"http:\/\/www.bernd-leitenberger.de\/blog\/?p=2873"},"modified":"2010-06-14T08:05:28","modified_gmt":"2010-06-14T06:05:28","slug":"obamas-plan","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2010\/06\/15\/obamas-plan\/","title":{"rendered":"Obamas Plan"},"content":{"rendered":"<p>Wie bekannt hat Obama die NASA angewiesen, Constellation einzustellen und daf&uuml;r Vorarbeiten f&uuml;r eine sp&auml;tere bemannte Mission zu Mars und anderen Zielen anzugehen. Obwohl im NASA Budget wenig Konkretes steht und alle Mittel erst f&uuml;r die folgenden Jahre avisiert werden, also 2011 das nun ja genehmigt wird noch kaum etwas von den neuen Pl&auml;nen enth&auml;lt, gab es schon Kontroversen um den Plan.<\/p>\n<p>Im US Kongress gibt es eine Front von pro-Konstellation Bef&uuml;rwortern, vor allem Abgeordneten der Staaten, die heute vom Constellation Programm profitieren, indem sie Komponenten fertigen. Doch das ist nichts neues. Eine &auml;hnliche Fraktion ist auch f&uuml;r die Weiterf&uuml;hrung der Shuttle Fl&uuml;ge. Auch hier geht es um Arbeitspl&auml;tze. Wenn man von dieser Tatsache absieht (die leider in allen L&auml;ndern die Weltraumprogramme bestimmt), so gibt es auch andere Gr&auml;ben.<\/p>\n<p>Einen vorl&auml;ufigen H&ouml;hepunkt wurde vor einigen Wochen erreicht: Bei einer Anh&ouml;rung sprachen sich Neil Armstrong und Eugene Cernan gegen den neuen Plan aus: Armstrong:<!--more--><\/p>\n<p lang=\"en\"><em>&#8222;The issue facing this meeting has produced substantial turmoil among space advocates. So many normally knowledgeable people were completely astounded by the President?s proposal. Had the announcement been preceded by the typical review, analysis and discussion among the Executive branch, the agency, the congress, and all the other interested and knowledgeable parties, no member of this committee would have been surprised by the announcement of a new plan.? In this case, a normally collegial sector of society was split in many fragments, some focused on contracts and money, some on work force and jobs, some on technical choices.?? ?All because a few planners, with little or no space operations experience, attempted an end run on the normal process.?? ?It has been painful to watch.&#8220; <\/em><\/p>\n<p>Und Eugene Cernan wurde noch deutlicher:<\/p>\n<p lang=\"en\"><em>&#8222;And, when one examines details of the FY2011 budget proposal, nowhere is there to be found one penny allocated to support space exploration. Yes, there has been much rhetoric on transformative technology, heavy lift propulsion research, robotic precursor missions, significant investment in commercial crew and cargo capabilities, pursuit of cross-cutting space technology capabilities, climate change research, aeronautics R&amp;D, and education initiatives, all worthwhile endeavors in their own right. Yet nowhere do we find any mention of the Human Exploration of Space and nowhere do we find a commitment in dollars to support this all important national endeavor. We (Armstrong, Lovell and I) have come to the unanimous conclusion that this budget proposal presents no challenges, has no focus, and in fact is a blueprint for a mission to ?nowhere.&#8220;<\/em><\/p>\n<p>Das ist eigentlich nichts neues. Es gab schon vorher offene Briefe ehemaliger Astronauten der Pr&auml;-Shuttle Area (sicher auch welcher dieser &Auml;ra, aber die sind weil es einige Hundert gibt nicht so bekannt), so von Jim Lovell, Scott Carpenter und anderen. Ein <a href=\"http:\/\/www.scottcarpenter.com\/openletter.htm\">offener Brief <\/a>von Scott Carpenter und anderen an Obama liest sich wie das &#8222;Who is Who&#8220; des Apollo Programms.<\/p>\n<p>Was neu ist, ist der Ton wie nun diskutiert wird. Elon Musk hat dabei den Vogel abgeschossen.<\/p>\n<p lang=\"en\"><em>&#8222;I?m sorry but I think Neil Armstrong is being manipulated. And it is a sorry sight indeed. Because he is of course a national hero. On the other hand, Buzz Aldrin?you know, I think, you want to go back and look to national heroes on advise for the future of space, there?s Neil Armstrong, who is a great man, and then there is Buzz Aldrin who is also a great man. Now, Buzz Aldrin is the guy with the PHD from MIT, and Neil is a pilot. He?s always been a pilot, that?s cool. But if you are going to look for somebody to render a judgement, a technical judgement on what program makes the most sense, I think you would probably pick the PHD from MIT, rather than the pilot. And Buzz Aldrin, the PHD from MIT, is the one who is a huge fan of the Obama policy.&#8220;<\/em><\/p>\n<p>Da wird also der Mann, der die Gemini 8 Mission rettete, mit den geringsten Treibstoffreserven aller Apollomissionen landete und nebenbei (wie Michel Van bemerkte) nicht nur einen Bachelor besitzt sondern auch die Doktorw&uuml;rde und den Professortitel als &#8222;just a Pilot&#8220; und &#8222;manipulated&#8220; bezeichnet. Pers&ouml;nlich verbuche ich den letzten Falcon Flug daher auch unter der Rubrik &#8222;Kleine S&uuml;nden bestraft Gott sofort&#8220;: Armstrong rettete Gemini 8, als die Kapsel in eine Rotation geriet und so jemand h&auml;tte wohl auch SpaceX bei der kosntruktion ihreer Tr&auml;gerrakete brauchen k&ouml;nnen, die offensichtlich auch unkontrolliert rotierte. Von Musk hielt ich schon vorher nicht viel. Mittlerweile ist er bei mir aber v&ouml;llig unten durch. Er schadet mit diesem unqualifizierten und unversch&auml;mten &Auml;u&szlig;erung auch dem Ruf seiner Firma die ja praktisch nur durch ihn &ouml;ffentlich wahrgenommen wird.<\/p>\n<p>Warum polarisiert nun Obamas Plan so? Auf der einen Seite ist es nat&uuml;rlich das Einstellen von Constellation. Die Reaktion verwundert mich aber. Wie Armstrong ja andeutet, ist das Constellation Programm auch schon bisher umstritten. Die Augustine Komission untersuchte die finanzielle Situation und stellte fest, dass es unterfinanziert ist und wenn sich nichts &auml;ndert eine Mondlandung sich um ein Jahrzehnt verz&ouml;gern k&ouml;nnte. Dabei ging sie noch vom Einstellen der ISS nach lediglich 5 Jahren Betrieb aus.<\/p>\n<p>Die ISS Einstellen will eigentlich keiner, aber noch mehr Mittel f&uuml;r Constellation ausgeben auch nicht. Dar&uuml;ber hinaus war Constellation ja schon in der NASA nicht unumstritten. Es gab Alternative Vorschl&auml;ge f&uuml;r die Tr&auml;gerraketen (Stichwort <a href=\"http:\/\/www.directlauncher.com\/\">Direct<\/a>), aber auch am Zeitplan und der Umsetzung &#8211; so erschien das Programm am Schluss nur noch als eine Wiederholung von Apollo und alles was dar&uuml;ber hinausging war auf unbestimmte Zeit verschoben. Das es mit Constellation so nicht weitergehen konnte war also klar. Es wurde auch spekuliert, dass nach dem Bericht der Augustine Kommission Teile des Constellation Programms eingestellt werden, wahrscheinlich die Ares V und der Altair Mondlander. Die Ares I und Orion wurden dagegen als wichtig f&uuml;r die ISS angesehen und einen bemannten Zugang zum Weltraum. Zumindest den Review des Programmes gab es also schon. Nur eben keine Diskussion was zu &auml;ndern w&auml;re, sondern eine alleinige Entscheidung. Warum auch nicht? Eine Entscheidung f&uuml;r ein Programm darf wohl ein Pr&auml;sident f&auml;llen, aber es nicht mehr alleine entscheiden? Sie wissen schon warum &#8211; es geht um Gelder und Arbeitspl&auml;tze, weshalb bei der Einstellung gerne alle mitreden wollen.<\/p>\n<p>Das es nun vollst&auml;ndig eingestellt wurde, ist sicherlich &uuml;berraschend. Es ist auch in meinen Augen nicht logisch. Zumindest was die Ares I und Orion betrifft. Denn das es ein eigenst&auml;ndiger Zugang zur ISS ben&ouml;tigt wird, ist ja unstrittig. Ob es nun schneller und billiger geht, einfach die Orion\/Ares abzubrechen und neu anzufangen? Ich bin skeptisch, da ich die Maxime &#8222;Privat = billiger und schneller&#8220; nicht f&uuml;r automatisch richtig halte. Ich glaube dass zwar eine Firma alleine durch die fehlende R&uuml;cksprache mit einer Raumfahrtbeh&ouml;rde (zus&auml;tzliche B&uuml;rokratieschicht \/ Zeitverlust) und fehlende Restriktionen (z.B. daf&uuml;r zu sorgen, dass bestimmte Staaten bestimmte Mittel erhalten) das Potential hat, einiges billiger zu machen und auch schneller. Doch dem muss man rund 6 Milliarden Dollar und 5 Jahre Vorarbeiten bei Ares I\/Orion gegenrechnen.<\/p>\n<p>Nun arbeitet die NASA ja auch noch an beidem weiter und das endg&uuml;ltige aus ist noch nicht beschlossen. Doch was ist Obamas Plan wirklich? Auch wenn es anders klingt, es ist schon die Einstellung aller Bem&uuml;hungen &uuml;ber den Erdorbit hinaus. Die Auftr&auml;ge f&uuml;r Technologieforschung, Triebwerken f&uuml;r Schwerlastraketen und unbemannte Forschung sind gewisserma&szlig;en Feigenbl&auml;tter, damit der Aufschrei nicht zu stark ist, denn wie schon erw&auml;hnt, es h&auml;ngen ja immer Arbeitspl&auml;tze an Programmen. Es ist aber auch Sicherheit: Sicherheit f&uuml;r die bisherigen Programme. Die ISS kann nun bis 2020 betrieben werden, &uuml;ber 2028 wird schon beraten. Das Shuttle kann koordiniert auslaufen ohne Zeitdruck.<\/p>\n<p>Worauf der fast alleinige Fokus liegt ist der private Mannschaftstransport. Wer wei&szlig;, was die USA bisher f&uuml;r Constellation, ISS und Shuttle ausgegeben haben, der wei&szlig;, dass man da Unsummen verdienen kann. Ein Frachttransporter ist lukrativ, aber nichts im Vergleich zu einem Mannschaftstransporter. Davon braucht man sicher pro Jahr etwa 4-6 St&uuml;ck, wenn jeweils drei Mann zur ISS fliegen. Auf diese privaten kommerziellen Auftr&auml;ge spekulieren nun mindestens vier Firmen und da leuchten schon die Dollarzeichen bei den Statements auf. Vor allem weil es so laufen wird, wie schon bei COTS: Die NASA zahlt die Entwicklungskosten und sp&auml;ter noch f&uuml;r die Fl&uuml;ge. Wenn dann die NASA zum Schluss kommt, dass eine Firma doch kein Raumschiff bauen kann, das brauchbar w&auml;re, dann gab es schon bis zu diesem Zeitpunkt Milliarden von der NASA. So hat SpaceX vor dem ersten COTS Demo Flug schon 349 Millionen von der NASA erhalten. 80 % der COTS Gesamtsumme und 101 Millionen aus dem Transportvertrag. Und selbst wenn es nicht sicher genug f&uuml;r die NASA ist, so kann man es ja noch an Weltraumtouristen vermieten oder als Frachter nutzen.<\/p>\n<p>Aber ich sehe eigentlich keine fundamentale &Auml;nderung in der NASA Politik. Immer noch zahlt die NASA und eine Firma entwickelt. Der Unterschied ist nur, dass bisher die NASA auch das Design festlegt und die Firma st&auml;rker &uuml;berwachte. Eine fundamentale &Auml;nderung w&auml;re es, wenn die NASA sagen w&uuml;rde: &#8222;Das sind die Spezifikationen unseres Raumschiffs in Bezug auf Kapazit&auml;t, Sicherheit etc.&#8220;, sagt was ihr haben wollt, wenn ihr &uuml;ber 10 Jahre vier Fl&uuml;ge pro Jahr garantiert bekommt&#8220;. Bezahlt w&uuml;rde dann f&uuml;r erbrachte Leistungen wobei der Hersteller dann seine Entwicklungskosten auf die Fl&uuml;ge umlegen m&uuml;sste. Das w&auml;re wirklich &#8222;privat&#8220;. Hat er sich verkalkuliert oder funktioniertt es nicht, so ist es sein Risiko. Doch bisher ist nach wie vor alles wie beim alten, nur leicht ver&auml;ndert.<\/p>\n<p>Meine Pers&ouml;nliche Meinung: Das Streichen der &Uuml;ber-LEO F&auml;higkeiten von Constellation ist richtig. Ich h&auml;tte auch die Ares I eingestellt und eine Orion gebaut die kompatibel mit Delta IV und Atlas V ist und dabei sowohl das beste aus den bisher verf&uuml;gbaren Tr&auml;gern wie auch den Investitionen in die Orion gezogen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie bekannt hat Obama die NASA angewiesen, Constellation einzustellen und daf&uuml;r Vorarbeiten f&uuml;r eine sp&auml;tere bemannte Mission zu Mars und anderen Zielen anzugehen. Obwohl im NASA Budget wenig Konkretes steht und alle Mittel erst f&uuml;r die folgenden Jahre avisiert werden, also 2011 das nun ja genehmigt wird noch kaum etwas von den neuen Pl&auml;nen enth&auml;lt, [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[204,352,1191,1136,16,32],"class_list":["post-2873","post","type-post","status-publish","format-standard","hentry","category-raumfahrt","tag-ares","tag-constellation","tag-eugene-cernan","tag-neil-armstrong","tag-obama","tag-orion","entry"],"a3_pvc":{"activated":false,"total_views":686,"today_views":0},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":18465,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/11\/07\/neues-zu-artemis-blue-origin-und-spacex\/","url_meta":{"origin":2873,"position":0},"title":"Neues zu Artemis, Blue Origin und SpaceX","author":"Bernd Leitenberger","date":"7. November 2025","format":false,"excerpt":"Hallo. Ich wei\u00df, ich habe mich in den letzten Wochen etwas rar gemacht. Ich hatte zum einen viel zu tun, dann noch eine OP am Handgelenk, etwas an meinem Buch geschrieben und derzeit ist auch meine Winterdepression wieder st\u00e4rker, sodass ich lieber spiele als Artikel zu verfassen. Es hat sich\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg04.met.vgwort.de\/na\/76454a00a29844c79745dc13a13341de","width":350,"height":200},"classes":[]},{"id":15301,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2021\/04\/20\/nachlese-zum-human-landing-system-hls-kontrakt\/","url_meta":{"origin":2873,"position":1},"title":"Nachlese zum Human Landing System (HLS) Kontrakt","author":"Bernd Leitenberger","date":"20. April 2021","format":false,"excerpt":"\ufeffWie bereits bekannt und hier auch schon kommentiert, hat die NASA am Wochenende SpaceX den Vertrag \u00fcber das HLS in einer H\u00f6he von 2,89 Milliarden Dollar vergeben. Ich habe zuerst \u00fcberlegt, ob ich das in der Aprilnachlese zu SpaceX thematisieren sollte, aber da die Kritik daran eigentlich nur teilweise mit\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/352f2778c491440a9f73c731c5880d09","width":350,"height":200},"classes":[]},{"id":4557,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2011\/04\/03\/atom-und-wahlnachlese\/","url_meta":{"origin":2873,"position":2},"title":"Atom- und Wahlnachlese","author":"Bernd Leitenberger","date":"3. April 2011","format":false,"excerpt":"Nun einige Wochen nach dem Super-Gau von Japan wird es an der Zeit f?r eine Nachlese und zwar eine etwas allgemeiner gehaltene. Ich m?chte an dieser Stelle mal meine Einstellung zur Kernkraft in den letzten Jahrzehnten reflektieren. Ich war urspr?nglich f?r Kernkraft. Wie viele andere, glaubte ich an umweltfreundliche Energie\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18605,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/03\/13\/artemis-berechnungen\/","url_meta":{"origin":2873,"position":3},"title":"Artemis-Berechnungen","author":"Bernd Leitenberger","date":"13. M\u00e4rz 2026","format":false,"excerpt":"Wie ihr vielleicht schon mitbekommen habt, gibt es im Artemisprogramm Neuigkeiten. Da wurde zuerst eine neue Erdorbitmission zur Erprobung der Lander eingeschoben, Artemis III wird also nicht auf dem Mond landen. Die zweite Neuerung war das die Oberstufe EUS wegf\u00e4llt. Zuerst mal dazu. Ein Bericht des OMG, so eine Art\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg07.met.vgwort.de\/na\/8003982d62154aaf9914aedb1248c232","width":350,"height":200},"classes":[]},{"id":18547,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/03\/04\/quo-vadis-artemis\/","url_meta":{"origin":2873,"position":4},"title":"Quo Vadis Artemis?","author":"Bernd Leitenberger","date":"4. M\u00e4rz 2026","format":false,"excerpt":"Ich muss mal meine nicht vorhandene humanistische Bildung heraush\u00e4ngen, sprich Latein kann ich nicht, aber ich habe in meiner Jugend gerne Monumentalschinken angeschaut und da gibt es den ber\u00fchmtem Film \"Quo Vadis\" mit der ersten gro\u00dfen Rolle f\u00fcr Peter Ustinov als Nero. Das Zitat ist bekannt: Petrus flieht aus Rom,\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"\/img\/artemis-2026-2028.jpg","width":350,"height":200,"srcset":"\/img\/artemis-2026-2028.jpg 1x, \/img\/artemis-2026-2028.jpg 1.5x, \/img\/artemis-2026-2028.jpg 2x, \/img\/artemis-2026-2028.jpg 3x, \/img\/artemis-2026-2028.jpg 4x"},"classes":[]},{"id":5216,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2011\/08\/10\/fcea2\/","url_meta":{"origin":2873,"position":5},"title":"FCEA2","author":"Bernd Leitenberger","date":"10. August 2011","format":false,"excerpt":"CEA2 (Chemical Equilibrium with Applications) ist ein seit gut 30 Jahren entwickeltes NASA Programm mit dem verschiedenste Probleme bei Gasphasen berechnet werden k\u00f6nnen. Ich beschr\u00e4nke mich auf das, was Raumfahrtliebhaber wohl am meisten machen: Die Berechnung der Performance von Triebwerken bei Raketen. Ich will die Benutzung des Programmes einmal erl\u00e4utern,\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/89efc24160614a1a93d97d19447e81a6","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/2873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=2873"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/2873\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=2873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=2873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=2873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}