{"id":6126,"date":"2012-03-31T00:39:18","date_gmt":"2012-03-30T22:39:18","guid":{"rendered":"http:\/\/www.bernd-leitenberger.de\/blog\/?p=6126"},"modified":"2012-03-29T23:43:44","modified_gmt":"2012-03-29T21:43:44","slug":"phobos-grunt-die-nachlese","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2012\/03\/31\/phobos-grunt-die-nachlese\/","title":{"rendered":"Phobos Grunt &#8211; die Nachlese"},"content":{"rendered":"<dl>\n<dt>Nun ist der Untersuchungsbericht raus, genauer gesagt, schon seit fast zwei Monaten. Doch da er nur in russsich herauskam habe ich mal abgewartet was andere &uuml;ber ihn schreiben und wie sie ihn beurteilen, auch weil die Nomenklatur der K&uuml;rzel es fast unm&ouml;glich macht mit einer einfachen &Uuml;bersetzung zu arbeiten.\u00a0Zeit also den Fehlschlag zu analysieren. Der Bericht der Untersuchungskommission, der schon im Februar vorlag, f&uuml;hrt als prim&auml;re Ursache den simultanen Reboot von zwei \u201eArbeitskan&auml;len\u201c (Elektronikmodulen) des Bordcomputers aus. Verantwortlich f&uuml;r den Reboot waren aber Ausf&auml;lle von Elektronikkomponenten durch kosmische Strahlung, die wiederum nur m&ouml;glich waren, weil nicht weltraumtaugliche Teile verwendet wurden. Es handelte sich im Detail um 512 K x 32 Bit SRAM-Chips des Typs <span style=\"color: #222222;\">WS512K32V20G2TM, die in beiden Platinen des Bordcompute<\/span>rs verbaut waren. Diese Chips sind nach \u00a0Steven McClure vom JPL, Schirmherr der Radiation Effects Group nicht strahlengeh&auml;rtet. Es handelt sich um Chips mit h&ouml;heren Grenzwerten gegen&uuml;ber Temperatur und anderen Umgebungseinfl&uuml;ssen. Sie gen&uuml;gen der \u201eMilit&auml;rspezifikation\u201c f&uuml;r den Einsatz in Flugzeugen oder Lenkwaffen. Das bedeutet sie sind robuster als die herk&ouml;mmlichen Exemplare, da sie auch bei sehr hohen und sehr tiefen Temperaturen funktionieren m&uuml;ssen. Sie sind auch etwas strahlentoleranter, da Flugzeuge in der Stratosph&auml;re einer h&ouml;heren Strahlenbelastung ausgesetzt sind. Sie sind allerdings nicht strahlengeh&auml;rtet, also f&uuml;r den dauerhaften Einsatz im Weltraum vorgesehen. Der Einsatz w&auml;re nach \u00a0Steven McClure noch tolerierbar f&uuml;r Kurzzeitmissionen von einigen Tagen Dauer, nicht jedoch f&uuml;r eine mehrj&auml;hrige Marsmission.<!--more--><\/dt>\n<dt><\/dt>\n<dt><span style=\"color: #222222;\">Zehn Tage lang, so f&uuml;hrt der Bericht aus, war die Raumsonde unter Kontrolle des Autopiloten. Er hielt die Ausrichtung auf die Sonne und z&uuml;ndete dazu regelm&auml;&szlig;ig die Lageregelungsd&uuml;sen. Dadurch kamen die Anhebungen der Bahn w&auml;hrend der ersten Tage zustande. Erst danach gelang eine Kommunikation. Dabei wurde bei einem der kurzen &Uuml;berfl&uuml;ge das Kommunikationssystem nicht abgeschaltet, die Batterien entluden sich und die Ausrichtung auf die Sonne ging verloren. Nun war die Raumsonde verloren.<\/span><\/dt>\n<dt><\/dt>\n<dt>Wenn der Ausfall der Speicherchips die prim&auml;re Ursache war, dann w&auml;re die Mission aber in jedem Falle gescheitert, denn im Parkorbit befand sie sich noch unter den irdischen Strahlungsg&uuml;rteln. Sie war damit in einer Region, wo sie vor den meisten kosmischen Strahlen durch das Erdmagnetfeld gesch&uuml;tzt war. Der Roskomos Chef Popowkin machte daf&uuml;r den Moskauer Hersteller NPO Lawotschkin verantwortlich. Dieser h&auml;tte damit rechnen m&uuml;ssen, dass die Strahlung den Betrieb der Sonde st&ouml;rt. Die Verantwortlichen w&uuml;rden bestraft, k&uuml;ndigte Popowkin an.<\/dt>\n<dt><\/dt>\n<dt>Inoffizielle Kommentare von Ingenieuren gaben an, dass ein Gro&szlig;teil der 90.000 Chips weder auf Weltraumtauglichkeit gepr&uuml;ft wurde, noch daf&uuml;r qualifiziert waren. Weiterhin sei die Software schlampig programmiert worden und viele westliche Experten halten Softwarefehler f&uuml;r die wahrscheinlichere Ursache. Dass nicht weltraumtaugliche Hardware ausfallen kann, w&auml;re m&ouml;glich, aber das dies schon weniger als zwei Stunden nach dem Start erfolgt, ist dann doch \u201e&auml;u&szlig;erst unwahrscheinlich\u201c. Wie schon gesagt sind die 512 KByte SRAM Chips zwar nicht geeignet f&uuml;r lange Missionen, aber dass sich so schnell ein Ausfall ereignet, w&auml;re doch extrem viel Pech. Das dies nun bei beiden Bordcomputern gleichzeitig passiert und sie beide in einen Rebootzyklus geraten, ist dann noch unwahrscheinlicher und spricht vielmehr f&uuml;r einen systematischen Fehler, wahrscheinlich in der Software. W&auml;re dies nur bei einem der Computer vorgekommen, so w&auml;re die Sonde nicht blockiert gewesen.<\/dt>\n<dt>Unbestritten ist, dass es grundlegende Designm&auml;ngel gab, die nicht im Bericht genannt wurden. So f&auml;llt die Tatsache auf, dass russische Bodenstationen in den ersten Stunden nach dem Start gar keine M&ouml;glichkeit hatten, Phobos Grunt zu kontaktieren, solange sie sich in einer Erdumlaufbahn befand.<\/dt>\n<dt><\/dt>\n<\/dl>\n<p lang=\"de-DE\">In vielem wird der Kenner der russischen Raumfahrt an fr&uuml;here Fehlschl&auml;ge erinnert. Phobos 1+2 gingen verloren, weil die Raumsonden keine Software an Bord hatten, die sie bei Problemen in einen \u201esicheren Modus\u201c bringen. Derartige Systeme waren schon damals bei der NASA und ESA Standard. Sie tun nichts anderes, als die Raumsonde so zur Sonne auszurichten, dass ihre Energieversorgung gew&auml;hrleistet ist. Alle nicht notwendigen Systeme werden deaktiviert und die Sonde versucht die Erde zu kontaktieren.<\/p>\n<p lang=\"de-DE\">Mars 96 ging verloren, weil die Oberstufe die Raumsonde auf einer falschen Umlaufbahn entlie&szlig;, nachdem sie kurz nach der Z&uuml;ndung ihren Betrieb einstellte. Die Raumsonde spulte ihr vorgegebenes Programm ab. Sie verschlimmerte damit die Situation noch mehr, da sie nach der Z&uuml;ndung eine Umlaufbahn hatte, die sie beim ersten Durchlaufen des erdn&auml;chsten Punktes zerst&ouml;ren w&uuml;rde.<\/p>\n<p lang=\"de-DE\">Es zeigen sich hier Unterschiede in Kulturen. Nicht umsonst hei&szlig;en die Raumsonden offiziell \u201eautomatische Raumsonde\u201c. Der Start von Phobos Grunt, wie auch von Mars 96, verliefen nach einem festen Zeitplan. Er sah keinerlei Beeinflussung von Au&szlig;en, sowohl vom Boden, wie auch durch &auml;u&szlig;ere Ereignisse vor. Wie bei Mars 96 war es unm&ouml;glich, das Problem zu untersuchen und eventuell vom Boden aus eine erneute Z&uuml;ndung zu unternehmen. Phobos Grunt sollte ihre beiden Triebwerksz&uuml;ndungen autonom durchf&uuml;hren. Schlimmer noch, es war niemals geplant, in dieser Phase &uuml;berhaupt einzugreifen, weswegen die Bodenkontrolle auch nicht Phobos Grunt aktivieren konnte.<\/p>\n<p lang=\"de-DE\">Bei den Raumsonden des JPL gibt es vom Start an einen stetigen Datenstrom zur Erde, selbst wenn die Sonde nichts tut und nur passiver Passagier ist. Das ist keine Komfortfunktion, sondern wie der Fall von Phobos Grunt zeigt, notwendig, um selbst wenn eine Mission scheitert, &uuml;berhaupt zu wissen, was schief geht. Das allerdings auch die NASA Fehler machte, zeigt der Verlust des Mars Polar Landers, bei dem kein Funkkontakt w&auml;hrend der letzten Viertelstunde \u2013 der eigentlichen Landung &#8211; m&ouml;glich war. W&auml;re der n&auml;chste Lander nicht weitgehend baugleich gewesen, man h&auml;tte die Ursache der gescheiterten Landung wohl nie gefunden.<\/p>\n<p lang=\"de-DE\">Auch das der Untersuchungsbericht nur in Russisch ver&ouml;ffentlicht wurde ist ein R&uuml;ckfall in die Sowjet&auml;ra. Es gibt auch keine Website in Englisch mehr zu Phobos Grunt und selbst in russisch von offizieller Seite nur rudiment&auml;re Informationen. Das man so schnell nach Schuldigen sucht \u2013 erst im Ausland, nun wohl bei Lawotschkin und eine Bestrafung ank&uuml;ndigt, zeugt auch nicht von einem souver&auml;nen Umgang mit der Situation. Vielmehr sollte man sich fragen, warum nicht weltraumqualifizierte Hardware eingesetzt wurde und wahrscheinlich auch die Software nicht ausgereift war. Passend dazu vergab Roskosmos auch Chancen. Erst 12 Tage nach dem Start wurde die ESA um Hilfe gebeten. NASA und ESA verf&uuml;gen anders als Russland &uuml;ber zahlreiche Bodenstationen auf dem Flugpfad den Phobos Grunt w&auml;hrend der ersten Uml&auml;ufe folgt. Sie h&auml;tten die Telemetrie der Raumsonde empfangen k&ouml;nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nun ist der Untersuchungsbericht raus, genauer gesagt, schon seit fast zwei Monaten. Doch da er nur in russsich herauskam habe ich mal abgewartet was andere &uuml;ber ihn schreiben und wie sie ihn beurteilen, auch weil die Nomenklatur der K&uuml;rzel es fast unm&ouml;glich macht mit einer einfachen &Uuml;bersetzung zu arbeiten.\u00a0Zeit also den Fehlschlag zu analysieren. Der [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[469],"class_list":["post-6126","post","type-post","status-publish","format-standard","hentry","category-raumfahrt","tag-phobos-grunt","entry"],"a3_pvc":{"activated":false,"total_views":760,"today_views":0},"jetpack-related-posts":[{"id":18610,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/03\/27\/galileos-cds-teil-1\/","url_meta":{"origin":6126,"position":0},"title":"Galileos CDS &#8211; Teil 1","author":"Bernd Leitenberger","date":"27.03.2026","format":false,"excerpt":"Hall\u00f6chen, es wird Zeit das ich mich mal wieder melde. Es gab zwei Gr\u00fcnde, warum ich mich so rar gemacht habe. Das eine ist das es gerade nicht so viel aktuelles gibt, au\u00dfer einem Update zu Artemis, zu dem ich vielleicht noch etwas schreibe. W\u00e4hrend Trump das ganze Programm nach\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg07.met.vgwort.de\/na\/4fb81c7bafbd4d9d88b5695abdb33d29","width":350,"height":200},"classes":[]},{"id":18485,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/01\/13\/programm-437\/","url_meta":{"origin":6126,"position":1},"title":"Programm 437","author":"Bernd Leitenberger","date":"13.01.2026","format":false,"excerpt":"Ich wei\u00df, ich mache mich in den letzten Wochen etwas rar. Daf\u00fcr gibt es zwei Gr\u00fcnde. Da ist zum einen die gesamte politische Lage. Prim\u00e4r nat\u00fcrlich in dem Land des unbegrenzten Irrsinns. Wenn der Machthaber von Venezuela entf\u00fchrt wird und unter falscher Begr\u00fcndung angeklagt wird - weil es ja in\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/3d6eb16326d743baa56f5ece884b5d21","width":350,"height":200},"classes":[]},{"id":14114,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2019\/07\/19\/apollo-jubilaeen-im-wandel-der-zeiten\/","url_meta":{"origin":6126,"position":2},"title":"Apollo Jubil&auml;en im Wandel der Zeiten","author":"Bernd Leitenberger","date":"19.07.2019","format":false,"excerpt":"Als ich mir mal die Sendungen anschaute die derzeit zum 50-sten Jubil\u00e4um der Landung von Apollo 11 kamen fielen mir Unterschiede auf. Nat\u00fcrlich legt man zu jedem Zeitpunkt den Wert auf andere Dinge, man hat aber auch eine andere Sicht, weil man historische Ereignisse anders, aus der Sicht von \u201ejetzt\u201c\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg07.met.vgwort.de\/na\/dcdc7b57dc4f40ada4b4433d4ee21d14","width":350,"height":200},"classes":[]},{"id":17895,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/01\/19\/nachlese-teststart-starship-itf-7\/","url_meta":{"origin":6126,"position":3},"title":"Nachlese Teststart Starship ITF-7","author":"Bernd Leitenberger","date":"19.01.2025","format":false,"excerpt":"Die erste Phase lief noch nach Plan. Das Starship mit der Seriennummer S33 und die SuperHeavy mit der Seriennummer B14 hoben mit 37 Minuten Versp\u00e4tung um 4:37 nachmittags lokaler Zeit ab. Der Flug selbst hatte einen genehmigten Startzeitraum von 10. bis zum 17. Januar 2025 mit jeweils einem Startfenster pro\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/60231369830445f0b5712ad7af8fdc7a","width":350,"height":200},"classes":[]},{"id":18419,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/10\/02\/der-neue-rekordhalter-bei-der-bemannten-raumfahrt\/","url_meta":{"origin":6126,"position":4},"title":"Der neue Rekordhalter bei der bemannten Raumfahrt","author":"Bernd Leitenberger","date":"02.10.2025","format":false,"excerpt":"\u2026 ist unfreiwillig Oleg Popolow. Die Geschichte zeigt, wo Russland heute in der Raumfahrt steht. Sie beginnt am 22. September 2022. Russland f\u00fchrt seit rund sieben Monaten Krieg gegen die Ukraine und hat Tausende Gefallene, Verwundete und gefangene Soldaten zu beklagen. Um die Verluste auszugleichen, wurde an diesem Tag eine\u2026","rel":"","context":"In &quot;M\u00fcnchhausens Kolumne&quot;","block_context":{"text":"M\u00fcnchhausens Kolumne","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/satire\/muenchhausen\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/6566478af4c24587a85b9f439288056d","width":350,"height":200},"classes":[]},{"id":18469,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/11\/13\/operation-fishbowl\/","url_meta":{"origin":6126,"position":5},"title":"Operation Fishbowl","author":"Bernd Leitenberger","date":"13.11.2025","format":false,"excerpt":"Hallo, ich schreibe weiter an meinem Buch, die Auskopplung der Thor und Delta aus dem Buch \u00fcber die US-Tr\u00e4gerraketen. Und wie immer nutze ich die Zeit noch was zu erg\u00e4nzen. Seitens des Einsatzes der Thor bzw. Delta als Satellitentr\u00e4ger gibt es wenig Neues zu schreiben da habe ich schon beim\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg","width":350,"height":200,"srcset":"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1x, https:\/\/upload.wikimedia.org\/wikipedia\/commons\/e\/e2\/Radiocarbon_bomb_spike.svg 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/6126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=6126"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/6126\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=6126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=6126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=6126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}