{"id":6337,"date":"2012-05-28T00:34:48","date_gmt":"2012-05-27T22:34:48","guid":{"rendered":"http:\/\/www.bernd-leitenberger.de\/blog\/?p=6337"},"modified":"2012-05-27T17:59:30","modified_gmt":"2012-05-27T15:59:30","slug":"gluckwunsch-spacex","status":"publish","type":"post","link":"https:\/\/www.bernd-leitenberger.de\/blog\/2012\/05\/28\/gluckwunsch-spacex\/","title":{"rendered":"Gl&uuml;ckwunsch SpaceX!"},"content":{"rendered":"<p>So so ich soll also SpaceX Gl&uuml;ckw&uuml;nsche &uuml;bermitteln? &Auml;h Leute, das ist ein Blog, so eine Mischung zwischen Kommentarspalte einer Zeitung und Leserbriefseite. Findet ihr da auch Gl&uuml;ckw&uuml;nsche an Merkel zu ihrer Politik? Wer einmal die Blogsuchfunktion bem&uuml;ht, wird feststellen es gab unter\u00a01766 ver&ouml;ffentlichten Blogs keinen einzigen mit einem Gl&uuml;ckwunsch zu einem Raumfahrtprojekt. Nicht mal zu denen, mit denen ich mich wegen meiner B&uuml;cher intensiv auseinandergesetzt habe. Ich habe mal beim Schwimmen dr&uuml;ber nachgedacht. Vielleicht sollte man wirklich manchen Leuten gratulieren. Vielleicht denen vom, JPL, die die Voyagers gebaut haben, die nun, 35 Jahre nach dem Start noch arbeiten. Also vielleicht gibt es im August einen weiteren Gl&uuml;ckwunsch-Blog.<!--more--><\/p>\n<p>Ich habe mir &uuml;berlegt ob ich diesen Blog satirisch aufziehen soll, schlie&szlig;lich ist ja bei SpaceX ne ganze Menge Realsatire drin. Doch dann vielen mir doch einige Dinge ein, f&uuml;r die ich Elon Musk und SpaceX wirklich ehrlich gratulieren kann.<\/p>\n<ul>\n<li>Gl&uuml;ckwunsch Elon Musk f&uuml;r die Frechheit Neil Armstrong seine Raumfahrtkompetenz anzusprechen, ihn &#8222;manipuliert&#8220; zu nennen und nur &#8222;einen Pilot&#8220; und dann, ohne das Du dich jemals daf&uuml;r entschuldigst hast zu fordern, dass er dich unterst&uuml;tzen soll.<\/li>\n<li>Gl&uuml;ckwunsch daf&uuml;r, dass ihr eine NASA-Pressemitteilung als eure ausgegeben habt und damit seit Jahren Schlagzeilen als &#8222;privates Raumfahrtunternehmen&#8220; macht und dies auch in Deutschland selbst seri&ouml;se Medien unkritisch &uuml;bernommen haben. Super, da f&uuml;r die NASA &#8222;private&#8220; bedeutet &#8222;nicht &ouml;ffentlich&#8220; das bedeutet, die NASA ist nur Kunde und entwickelt nicht mit. Das jeder nun meint Elon Musk w&uuml;rde die private Raumfahrt entwickeln ist ein echte Leistung an P&amp;R arbeit<\/li>\n<li>Gl&uuml;ckwunsch das ihr erkannt habt, dass die Masse mit einigen Videos und Twittermeldungen sowie vielen Ank&uuml;ndigungen abgespeist werden kann und das einem die Freiheit gibt alles m&ouml;gliche zu behaupten und wieder zur&uuml;ckzunehmen.<\/li>\n<li>Gl&uuml;ckwunsch daf&uuml;r, dass euch alle als private Firma ansehen, obwohl von euren bisher aufgebrachten Finanzmitteln nur 10% von Elon Musk aber 70% von der NASA und dem Dod stammen.<\/li>\n<li>Gl&uuml;ckwunsch Elon f&uuml;r seine politischen Kontakte. Es ist schon eine Leistung wenn einen Obama als einzigen besucht wenn er nach Cape Canaveral f&auml;hrt und er einen pers&ouml;nlich anruft. So haben sich die Ausgaben f&uuml;r Lobbyismus (dreimal h&ouml;her als bei ULA) doch gelohnt.<\/li>\n<li>Gl&uuml;ckwunsch, die Firma ist wohl angesichts dieser Kontakte gerettet. Schlie&szlig;lich hat die US-Regierung ja schon f&uuml;r Tesla Motors mit 465 Millionen Dollar geb&uuml;rgt. Selbst wenn ihr zahlungsunf&auml;hig seid, wird Obama wohl Anweisung geben euch zu retten. Bei General Motors hat das ja auch schon geklappt.<\/li>\n<li>Gl&uuml;ckwunsch, dass ihr die NASA sogar zum L&uuml;gen brachtest. Bei der Pressekonferenz zum Start hie&szlig; es noch, die NASA zahle nur noch beim CRS wenn &#8222;geliefert&#8220; wird, und wenige Tage sp&auml;ter erf&auml;hrt man, dass ihr schon 336,7 Millionen Dollar von CRS erhalten hat (entsprechend zweieinhalb Fl&uuml;gen) obwohl noch kein einziger absolviert wurde.<\/li>\n<li>Gl&uuml;ckwunsch, dass ihr so unkritische Anh&auml;nger habt, die euch fanatisch verteidigen egal ob ihr Missionen zum Mars, auf den Punkt landende Stufen ank&uuml;ndigt, aber jede Wende in der Firmenpolitik mitmachen (Ihr wisst ja: Erst sollte die Falcon wiederverwendbar sein, dann habt ihr ne Falcon V, Falcon 1e und Falcon 9 block II angek&uuml;ndigt und nie gebaut).<\/li>\n<li>Gl&uuml;ckwunsch, dass ihr das Prinzip der inkrementellen Entwicklung aus dem Softwarebereich auf Raketen &uuml;bertragen habt und nun sogar Versionsnummern eingef&uuml;hrt habt.<\/li>\n<li>Gl&uuml;ckwunsch, dass ihr es schafftet, dass man an euch andere Ma&szlig;st&auml;be anlegt als an andere Firmen und Raumfahrtagenturen. Man sollte nur mal &uuml;berlegen, wie das Echo gewesen w&auml;re, wenn das ATV drei Fl&uuml;ge gebraucht h&auml;tte, bis er an die ISS andocken darf und erst beim vierten der regul&auml;re Einsatz begonnen h&auml;tte. Man h&auml;tte sich schiefgelacht. Aber ihr werdet gefeiert.<\/li>\n<li>Gl&uuml;ckwunsch dass ihr in Zeiten von GPS und Lidarger&auml;ten das heranfahren an die ISS bis auf 10 m als gro&szlig;e Leistung verkaufen k&ouml;nnt. Ihr solltet das als Dienstleistung f&uuml;r die Hersteller von Navis und Einparkhilfen anbieten. Bei denen ist das v&ouml;llig selbstverst&auml;ndlich und keine bejubelt sie.<\/li>\n<li>Gl&uuml;ckwunsch, dass jeder eure Zahlen und Angaben von der Homepage kritiklos &uuml;bernimmt, obwohl diese selbst im COTS Presskit widerspr&uuml;chlich sind und bei vielen Angaben man durch Dreisatz ihre Falschheit nachweisen kann. Na ja ich sollte eher dazu gratulieren, dass es kaum noch unabh&auml;ngige Fachleute gibt die eure Fehler erkennen k&ouml;nnten.<\/li>\n<li>Gl&uuml;ckwunsch, dass ihr es fertigbrachtet weitgehend unter Ausschluss der &Ouml;ffentlichkeit zu operieren und sogar Misserfolge geheim halten konntet, wie das euch Manager mit Erfahrung sofort wieder verlassen oder beim zweiten Falcon 9 Testflug ein Triebwerk ausfiel.<\/li>\n<li>Gl&uuml;ckwunsch Elon, dass Du nun &#8222;Chief Designer&#8220; geworden bist, und dies obwohl Du, wie Du bis heute beweist (ein defektes Druckventil durch &#8222;Softwareupdate&#8220; reparieren) keine blase Ahnung von der Raumfahrt oder Raketentechnik hast.<\/li>\n<\/ul>\n<p>Also ich glaube eure Zukunft ist gesichert. Selbst wenn das Schnellballsystem nicht aufgeht (so wie ich es ausgerechnet habe, m&uuml;sst ihr nun erst mal f&uuml;r rund 460 Millionen Dollar Auftr&auml;ge erf&uuml;llen, nicht gerade wenig, wenn eure gesamten Einnahmen in zehn Jahren bei 1,2 Milliarden Dollar lagen), so d&uuml;rftet ihr bei den engen Beziehungen in die h&ouml;chsten Kreise eben anders gerettet werden &#8211; siehe Tesla Motors&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So so ich soll also SpaceX Gl&uuml;ckw&uuml;nsche &uuml;bermitteln? &Auml;h Leute, das ist ein Blog, so eine Mischung zwischen Kommentarspalte einer Zeitung und Leserbriefseite. Findet ihr da auch Gl&uuml;ckw&uuml;nsche an Merkel zu ihrer Politik? Wer einmal die Blogsuchfunktion bem&uuml;ht, wird feststellen es gab unter\u00a01766 ver&ouml;ffentlichten Blogs keinen einzigen mit einem Gl&uuml;ckwunsch zu einem Raumfahrtprojekt. Nicht mal [&hellip;]<\/p>\n","protected":false},"author":169,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[2551,5],"class_list":["post-6337","post","type-post","status-publish","format-standard","hentry","category-raumfahrt","tag-gluckwunsch","tag-spacex","entry"],"a3_pvc":{"activated":false,"total_views":559,"today_views":0},"jetpack-related-posts":[{"id":13740,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2019\/02\/17\/die-2019-er-spacex-wette\/","url_meta":{"origin":6337,"position":0},"title":"Die 2019-er SpaceX Wette","author":"Bernd Leitenberger","date":"17.02.2019","format":false,"excerpt":"Wer mich kennt, wei\u00df, dass ich jedes Jahr eine Wette mit SpaceX eingehe. Das System ist eigentlich sehr einfach: Ich nehme nur eine SpaceX-Aussage und wette dagegen, also, dass sie nicht stimmt oder nicht erreicht wird. Das mache ich schon seit einigen Jahren und bisher habe ich mit einer Ausnahme\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg06.met.vgwort.de\/na\/7955f286a7004559b4ddbb5d8b481043","width":350,"height":200},"classes":[]},{"id":15301,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2021\/04\/20\/nachlese-zum-human-landing-system-hls-kontrakt\/","url_meta":{"origin":6337,"position":1},"title":"Nachlese zum Human Landing System (HLS) Kontrakt","author":"Bernd Leitenberger","date":"20.04.2021","format":false,"excerpt":"\ufeffWie bereits bekannt und hier auch schon kommentiert, hat die NASA am Wochenende SpaceX den Vertrag \u00fcber das HLS in einer H\u00f6he von 2,89 Milliarden Dollar vergeben. Ich habe zuerst \u00fcberlegt, ob ich das in der Aprilnachlese zu SpaceX thematisieren sollte, aber da die Kritik daran eigentlich nur teilweise mit\u2026","rel":"","context":"In &quot;Raumfahrt&quot;","block_context":{"text":"Raumfahrt","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/"},"img":{"alt_text":"","src":"https:\/\/vg01.met.vgwort.de\/na\/352f2778c491440a9f73c731c5880d09","width":350,"height":200},"classes":[]},{"id":18385,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2025\/09\/07\/spacex-splitter\/","url_meta":{"origin":6337,"position":2},"title":"SpaceX-Splitter","author":"Bernd Leitenberger","date":"07.09.2025","format":false,"excerpt":"Der heutige Blog ist nicht neu, das, was ich schreibe habe ich schon einige Male geschrieben, aber ebenso wie ich zum wiederholten Male Artikel \u00fcber den Fortschritt oder fehlenden Fortschritt in anderen Webseiten lese, denke ich kann man einiges noch mal aufkochen. Ich will das als eine Folge von fiktiven\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg02.met.vgwort.de\/na\/b2e94ef07fec4d7190886846bcbb4589","width":350,"height":200},"classes":[]},{"id":18709,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/06\/14\/der-blog-wird-20\/","url_meta":{"origin":6337,"position":3},"title":"Der Blog wird 20","author":"Bernd Leitenberger","date":"14.06.2026","format":false,"excerpt":"Vor genau 20 Jahren erschien der erste Blog, damals noch unter der Bezeichnung \u201eWeb-Log\u201c. Ich habe gerade einen Artikel gelesen \u00fcber das Zustandekommen des Worts \u201eBlog\u201c. Interessanterweise war es genauso wie bei mir. Obwohl es die Bezeichnung \u201eBlog\u201c damals schon gab, bezeichnete ich meinen Blog lange Zeit als \u201eWeb-Log\u201c, also\u2026","rel":"","context":"In &quot;Allgemein&quot;","block_context":{"text":"Allgemein","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/allgemein\/"},"img":{"alt_text":"","src":"https:\/\/vg09.met.vgwort.de\/na\/635ab0c6229b4d6898fff3de77fa418a","width":350,"height":200},"classes":[]},{"id":18820,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2026\/08\/16\/raketenentwicklung-nach-dogma-anstatt-wissenschaft-2\/","url_meta":{"origin":6337,"position":4},"title":"Raketenentwicklung nach Dogma anstatt Wissenschaft (2)","author":"Bernd Leitenberger","date":"16.08.2026","format":false,"excerpt":"Kommen wir nun zum Starship. Im ersten Teil habe ich beschrieben, wie Elon Musk das Dogma \u201eWiederverwendung\u201c bei der Falcon\u202f9 durchsetzte. Die Falcon\u202f9 war nicht f\u00fcr die Wiederverwendung ausgelegt. SpaceX hat auch keine Computersimulationen gemacht, um die Konstruktion auf die zu erwartenden Lasten zu optimieren, die viel h\u00f6her als beim\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/vg04.met.vgwort.de\/na\/77ceed95fbe443b0a0ab1fc66656dfd4","width":350,"height":200},"classes":[]},{"id":16773,"url":"https:\/\/www.bernd-leitenberger.de\/blog\/2023\/05\/07\/die-spacex-wetten\/","url_meta":{"origin":6337,"position":5},"title":"Die SpaceX Wetten","author":"Bernd Leitenberger","date":"07.05.2023","format":false,"excerpt":"Da immer wieder behauptet wird ich h\u00e4tte alle meine Wetten verloren, habe ich mir mal die M\u00fche gemacht alle zusammenzusuchen (nun ja alle die ich finden konnte, wer noch weitere findet bitte hier einen Kommentar mit Link bloggen: 4.10.2008: Wette das ich die Falcon 9 Nutzlast genauer berechnen kann als\u2026","rel":"","context":"In &quot;SpaceX&quot;","block_context":{"text":"SpaceX","link":"https:\/\/www.bernd-leitenberger.de\/blog\/category\/raumfahrt\/spacex\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.bernd-leitenberger.de\/img\/starship-v4-tabelle.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.bernd-leitenberger.de\/img\/starship-v4-tabelle.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.bernd-leitenberger.de\/img\/starship-v4-tabelle.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.bernd-leitenberger.de\/img\/starship-v4-tabelle.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/users\/169"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/comments?post=6337"}],"version-history":[{"count":0,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/posts\/6337\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/media?parent=6337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/categories?post=6337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bernd-leitenberger.de\/blog\/wp-json\/wp\/v2\/tags?post=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}